{"id":10512,"date":"2024-09-23T13:10:59","date_gmt":"2024-09-23T16:10:59","guid":{"rendered":"https:\/\/astroceap.com.br\/ceap\/?p=10512"},"modified":"2024-10-28T17:36:46","modified_gmt":"2024-10-28T20:36:46","slug":"%f0%9f%8c%ba-bem-vinda-primavera-comecou","status":"publish","type":"post","link":"https:\/\/astroceap.com.br\/ceap\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\/","title":{"rendered":"\ud83c\udf3a BEM VINDA PRIMAVERA! COME\u00c7OU!"},"content":{"rendered":"<p><img decoding=\"async\" class=\"size-medium wp-image-10513 aligncenter lazyload\" data-src=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2024\/09\/banner_sol_libra-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" data-srcset=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2024\/09\/banner_sol_libra-300x300.jpg 300w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2024\/09\/banner_sol_libra-1024x1024.jpg 1024w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2024\/09\/banner_sol_libra-150x150.jpg 150w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2024\/09\/banner_sol_libra-768x768.jpg 768w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2024\/09\/banner_sol_libra-230x230.jpg 230w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2024\/09\/banner_sol_libra-330x330.jpg 330w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2024\/09\/banner_sol_libra.jpg 1280w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><\/p>\n<p>&nbsp;<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><span style=\"color: #000000;\"><span class=\"html-span xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x3nfvp2 x1j61x8r x1fcty0u xdj266r xat24cr xgzva0m xhhsvwb xxymvpz xlup9mm x1kky2od\"><img decoding=\"async\" class=\"xz74otr lazyload\" data-src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t71\/1\/16\/1f339.png\" alt=\"\ud83c\udf39\" width=\"16\" height=\"16\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/span>EQUIN\u00d3CIO &#8211; SOL EM LIBRA E V\u00caNUS EM ESCORPI\u00c3O<\/span><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><span style=\"color: #000000;\"><span class=\"html-span xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x3nfvp2 x1j61x8r x1fcty0u xdj266r xat24cr xgzva0m xhhsvwb xxymvpz xlup9mm x1kky2od\"><img decoding=\"async\" class=\"xz74otr lazyload\" data-src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t1e\/1\/16\/1f33f.png\" alt=\"\ud83c\udf3f\" width=\"16\" height=\"16\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/span> A primavera no HS come\u00e7ou neste domingo, dia 22\/09, \u00e0s 09:43 h, e para a astrologia, Equin\u00f3cios e Solst\u00edcios s\u00e3o marcadores importantes no c\u00e9u, neste caso de agora, quando o Sol ingressa no zero grau do signo de Libra, inaugurando um novo ciclo. \u00c9 um per\u00edodo astrol\u00f3gico que simboliza equil\u00edbrio e harmonia!<\/span><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><span style=\"color: #000000;\">Interessante notarmos que este ingresso do Sol em Libra est\u00e1 se dando concomitante com o ingresso da V\u00eanus no signo de Escorpi\u00e3o, e numa quadratura com Plut\u00e3o, sendo que a V\u00eanus \u00e9 dispositora deste Sol em Libra. Em outras palavras, busca-se a harmonia e a equanimidade, mas ao mesmo tempo isso n\u00e3o se d\u00e1 facilmente, pois existem imposi\u00e7\u00f5es, conflitos, dom\u00ednios e jogos de poder.<\/span><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><span style=\"color: #000000;\">Como aproveitar o lado bom e saud\u00e1vel das rela\u00e7\u00f5es e das trocas amorosas, sem cair em situa\u00e7\u00f5es intensas, de amea\u00e7as, vingan\u00e7as ou de posturas impositivas?<\/span><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><span style=\"color: #000000;\">Assim como a flora\u00e7\u00e3o das \u00e1rvores na primavera simboliza fecundidade e renova\u00e7\u00e3o, uma forma melhor de se navegar neste momento seria atrav\u00e9s do equil\u00edbrio e da harmonia da esta\u00e7\u00e3o, mas tamb\u00e9m simultaneamente com movimentos de transforma\u00e7\u00f5es e regenera\u00e7\u00f5es, assim como esta V\u00eanus, protagonista deste momento, est\u00e1 pedindo<\/span><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; EQUIN\u00d3CIO &#8211; SOL EM LIBRA E V\u00caNUS EM ESCORPI\u00c3O A primavera no HS come\u00e7ou neste domingo, dia 22\/09, \u00e0s 09:43 h, e para a astrologia, Equin\u00f3cios e Solst\u00edcios s\u00e3o marcadores importantes no c\u00e9u, neste caso de agora, quando o<\/p>\n","protected":false},"author":8,"featured_media":10587,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[23],"tags":[115,114,110,133,37,136,74,338,404,280,44,139,72,246,268,40,43,158,134,221,38,46,135,42,294,142,181,405,141,145],"class_list":["post-10512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-cursodeastrologia","tag-cursosdeastrologia","tag-zodiaco","tag-ascendente","tag-astrologia","tag-astrologiapsicologica","tag-autoconhecimento","tag-direcionamento-de-vida","tag-equinociodeprimavera","tag-formacaoemastrologia","tag-horoscopo","tag-infernoastral","tag-jung","tag-marcia-ferreira","tag-marciaferreira","tag-mitologia","tag-planetas","tag-previsoes","tag-previsoesastrologicas","tag-primavera","tag-psicologia","tag-psicologia-analitica","tag-quatroelementos","tag-signos","tag-signosdozodiaco","tag-sinastria","tag-sol","tag-solemlibra","tag-transitosastrologicos","tag-venus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\ud83c\udf3a BEM VINDA PRIMAVERA! COME\u00c7OU! - C.E.A.P.<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\udf3a BEM VINDA PRIMAVERA! COME\u00c7OU! - C.E.A.P.\" \/>\n<meta property=\"og:description\" content=\"&nbsp; EQUIN\u00d3CIO &#8211; SOL EM LIBRA E V\u00caNUS EM ESCORPI\u00c3O A primavera no HS come\u00e7ou neste domingo, dia 22\/09, \u00e0s 09:43 h, e para a astrologia, Equin\u00f3cios e Solst\u00edcios s\u00e3o marcadores importantes no c\u00e9u, neste caso de agora, quando o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astroceap.com.br\/ceap\/\ud83c\udf3a-bem-vinda-primavera-comecou\/\" \/>\n<meta property=\"og:site_name\" content=\"C.E.A.P.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/astroceap\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-23T16:10:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-28T20:36:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2024\/09\/blog_sol_em_libra.png\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Henrique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:site\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Henrique\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\\\/\"},\"author\":{\"name\":\"Henrique\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/ddb041600c30d210efaa7d497809f126\"},\"headline\":\"\ud83c\udf3a BEM VINDA PRIMAVERA! COME\u00c7OU!\",\"datePublished\":\"2024-09-23T16:10:59+00:00\",\"dateModified\":\"2024-10-28T20:36:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\\\/\"},\"wordCount\":231,\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/blog_sol_em_libra.png\",\"keywords\":[\"#cursodeastrologia\",\"#cursosdeastrologia\",\"#zod\u00edaco\",\"ascendente\",\"astrologia\",\"astrologiapsicologica\",\"autoconhecimento\",\"direcionamento de vida\",\"equinociodeprimavera\",\"formacaoemastrologia\",\"hor\u00f3scopo\",\"infernoastral\",\"Jung\",\"M\u00e1rcia Ferreira\",\"marciaferreira\",\"mitologia\",\"planetas\",\"previs\u00f5es\",\"previsoesastrologicas\",\"primavera\",\"psicologia\",\"psicologia anal\u00edtica\",\"quatroelementos\",\"signos\",\"signosdozodiaco\",\"sinastria\",\"sol\",\"solemlibra\",\"transitosastrologicos\",\"v\u00eanus\"],\"articleSection\":[\"BLOG\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\\\/\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\\\/\",\"name\":\"\ud83c\udf3a BEM VINDA PRIMAVERA! COME\u00c7OU! - C.E.A.P.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/blog_sol_em_libra.png\",\"datePublished\":\"2024-09-23T16:10:59+00:00\",\"dateModified\":\"2024-10-28T20:36:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\\\/#primaryimage\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/blog_sol_em_libra.png\",\"contentUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/blog_sol_em_libra.png\",\"width\":480,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\ud83c\udf3a BEM VINDA PRIMAVERA! COME\u00c7OU!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"name\":\"C.E.A.P.\",\"description\":\"Centro de Estudos de Astrologia Psicol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\",\"name\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"contentUrl\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"width\":140,\"height\":174,\"caption\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/astroceap\\\/\",\"https:\\\/\\\/x.com\\\/astrologiaceap\",\"https:\\\/\\\/www.instagram.com\\\/ceap.astrologia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDsKeXx5S7f2xoPUxNpARSQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/ddb041600c30d210efaa7d497809f126\",\"name\":\"Henrique\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g\",\"caption\":\"Henrique\"},\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/author\\\/henrique\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83c\udf3a BEM VINDA PRIMAVERA! COME\u00c7OU! - C.E.A.P.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"\ud83c\udf3a BEM VINDA PRIMAVERA! COME\u00c7OU! - C.E.A.P.","og_description":"&nbsp; EQUIN\u00d3CIO &#8211; SOL EM LIBRA E V\u00caNUS EM ESCORPI\u00c3O A primavera no HS come\u00e7ou neste domingo, dia 22\/09, \u00e0s 09:43 h, e para a astrologia, Equin\u00f3cios e Solst\u00edcios s\u00e3o marcadores importantes no c\u00e9u, neste caso de agora, quando o","og_url":"https:\/\/astroceap.com.br\/ceap\/\ud83c\udf3a-bem-vinda-primavera-comecou\/","og_site_name":"C.E.A.P.","article_publisher":"https:\/\/www.facebook.com\/astroceap\/","article_published_time":"2024-09-23T16:10:59+00:00","article_modified_time":"2024-10-28T20:36:46+00:00","og_image":[{"width":480,"height":300,"url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2024\/09\/blog_sol_em_libra.png","type":"image\/png"}],"author":"Henrique","twitter_card":"summary_large_image","twitter_creator":"@astrologiaceap","twitter_site":"@astrologiaceap","twitter_misc":{"Escrito por":"Henrique","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astroceap.com.br\/ceap\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\/#article","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\/"},"author":{"name":"Henrique","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/ddb041600c30d210efaa7d497809f126"},"headline":"\ud83c\udf3a BEM VINDA PRIMAVERA! COME\u00c7OU!","datePublished":"2024-09-23T16:10:59+00:00","dateModified":"2024-10-28T20:36:46+00:00","mainEntityOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\/"},"wordCount":231,"publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2024\/09\/blog_sol_em_libra.png","keywords":["#cursodeastrologia","#cursosdeastrologia","#zod\u00edaco","ascendente","astrologia","astrologiapsicologica","autoconhecimento","direcionamento de vida","equinociodeprimavera","formacaoemastrologia","hor\u00f3scopo","infernoastral","Jung","M\u00e1rcia Ferreira","marciaferreira","mitologia","planetas","previs\u00f5es","previsoesastrologicas","primavera","psicologia","psicologia anal\u00edtica","quatroelementos","signos","signosdozodiaco","sinastria","sol","solemlibra","transitosastrologicos","v\u00eanus"],"articleSection":["BLOG"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/astroceap.com.br\/ceap\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\/","url":"https:\/\/astroceap.com.br\/ceap\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\/","name":"\ud83c\udf3a BEM VINDA PRIMAVERA! COME\u00c7OU! - C.E.A.P.","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\/#primaryimage"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2024\/09\/blog_sol_em_libra.png","datePublished":"2024-09-23T16:10:59+00:00","dateModified":"2024-10-28T20:36:46+00:00","breadcrumb":{"@id":"https:\/\/astroceap.com.br\/ceap\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astroceap.com.br\/ceap\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\/#primaryimage","url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2024\/09\/blog_sol_em_libra.png","contentUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2024\/09\/blog_sol_em_libra.png","width":480,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/astroceap.com.br\/ceap\/%f0%9f%8c%ba-bem-vinda-primavera-comecou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/astroceap.com.br\/ceap\/"},{"@type":"ListItem","position":2,"name":"\ud83c\udf3a BEM VINDA PRIMAVERA! COME\u00c7OU!"}]},{"@type":"WebSite","@id":"https:\/\/astroceap.com.br\/ceap\/#website","url":"https:\/\/astroceap.com.br\/ceap\/","name":"C.E.A.P.","description":"Centro de Estudos de Astrologia Psicol\u00f3gica","publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astroceap.com.br\/ceap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/astroceap.com.br\/ceap\/#organization","name":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica","url":"https:\/\/astroceap.com.br\/ceap\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/","url":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","contentUrl":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","width":140,"height":174,"caption":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/astroceap\/","https:\/\/x.com\/astrologiaceap","https:\/\/www.instagram.com\/ceap.astrologia\/","https:\/\/www.youtube.com\/channel\/UCDsKeXx5S7f2xoPUxNpARSQ"]},{"@type":"Person","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/ddb041600c30d210efaa7d497809f126","name":"Henrique","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g","caption":"Henrique"},"url":"https:\/\/astroceap.com.br\/ceap\/author\/henrique\/"}]}},"_links":{"self":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/10512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/comments?post=10512"}],"version-history":[{"count":1,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/10512\/revisions"}],"predecessor-version":[{"id":10514,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/10512\/revisions\/10514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media\/10587"}],"wp:attachment":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media?parent=10512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/categories?post=10512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/tags?post=10512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}