{"id":11003,"date":"2025-01-06T17:55:45","date_gmt":"2025-01-06T20:55:45","guid":{"rendered":"https:\/\/astroceap.com.br\/ceap\/?p=11003"},"modified":"2025-01-06T17:55:45","modified_gmt":"2025-01-06T20:55:45","slug":"2025-a-conjuncao-saturno-netuno-parte-2","status":"publish","type":"post","link":"https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/","title":{"rendered":"2025 &#8211; A CONJUN\u00c7\u00c3O SATURNO NETUNO &#8211; PARTE 2"},"content":{"rendered":"<p style=\"text-align: center;\"><iframe title=\"2025_parte_02\" data-src=\"https:\/\/player.vimeo.com\/video\/1044438185?badge=0&amp;autopause=0&amp;player_id=0&amp;app_id=58479\" width=\"340\" height=\"604\" frameborder=\"0\" src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">Nessa sequ\u00eancia de v\u00eddeos sobre 2025 estamos compreendendo tudo o diz respeito \u00e0 conjun\u00e7\u00e3o Saturno Netuno, que juntamente com Plut\u00e3o em Aqu\u00e1rio, \u00e9 o grande impacto desta d\u00e9cada. Neste v\u00eddeo, a parte 2 do sequencial de 5 v\u00eddeos, veremo um breve hist\u00f3rico de outros momentos na hist\u00f3ria em que houve essa conjun\u00e7\u00e3o e tamb\u00e9m individualmente, como poderemos lidar da melhor maneira poss\u00edvel com essa conjun\u00e7\u00e3o.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Nessa sequ\u00eancia de v\u00eddeos sobre 2025 estamos compreendendo tudo o diz respeito \u00e0 conjun\u00e7\u00e3o Saturno Netuno, que juntamente com Plut\u00e3o em Aqu\u00e1rio, \u00e9 o grande impacto desta d\u00e9cada. Neste v\u00eddeo, a parte 2 do sequencial de 5 v\u00eddeos, veremo<\/p>\n","protected":false},"author":8,"featured_media":11004,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[180],"tags":[115,114,110,379,133,37,136,74,338,280,44,72,246,268,40,122,43,158,134,38,46,135,92,42,294,142,181,141],"class_list":["post-11003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videos","tag-cursodeastrologia","tag-cursosdeastrologia","tag-zodiaco","tag-379","tag-ascendente","tag-astrologia","tag-astrologiapsicologica","tag-autoconhecimento","tag-direcionamento-de-vida","tag-formacaoemastrologia","tag-horoscopo","tag-jung","tag-marcia-ferreira","tag-marciaferreira","tag-mitologia","tag-netuno","tag-planetas","tag-previsoes","tag-previsoesastrologicas","tag-psicologia","tag-psicologia-analitica","tag-quatroelementos","tag-saturno","tag-signos","tag-signosdozodiaco","tag-sinastria","tag-sol","tag-transitosastrologicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2025 - A CONJUN\u00c7\u00c3O SATURNO NETUNO - PARTE 2 - C.E.A.P.<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2025 - A CONJUN\u00c7\u00c3O SATURNO NETUNO - PARTE 2 - C.E.A.P.\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Nessa sequ\u00eancia de v\u00eddeos sobre 2025 estamos compreendendo tudo o diz respeito \u00e0 conjun\u00e7\u00e3o Saturno Netuno, que juntamente com Plut\u00e3o em Aqu\u00e1rio, \u00e9 o grande impacto desta d\u00e9cada. Neste v\u00eddeo, a parte 2 do sequencial de 5 v\u00eddeos, veremo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/\" \/>\n<meta property=\"og:site_name\" content=\"C.E.A.P.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/astroceap\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-06T20:55:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/01\/img_destacada.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Henrique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:site\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Henrique\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2025-a-conjuncao-saturno-netuno-parte-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2025-a-conjuncao-saturno-netuno-parte-2\\\/\"},\"author\":{\"name\":\"Henrique\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/ddb041600c30d210efaa7d497809f126\"},\"headline\":\"2025 &#8211; A CONJUN\u00c7\u00c3O SATURNO NETUNO &#8211; PARTE 2\",\"datePublished\":\"2025-01-06T20:55:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2025-a-conjuncao-saturno-netuno-parte-2\\\/\"},\"wordCount\":83,\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2025-a-conjuncao-saturno-netuno-parte-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/img_destacada.png\",\"keywords\":[\"#cursodeastrologia\",\"#cursosdeastrologia\",\"#zod\u00edaco\",\"2025\",\"ascendente\",\"astrologia\",\"astrologiapsicologica\",\"autoconhecimento\",\"direcionamento de vida\",\"formacaoemastrologia\",\"hor\u00f3scopo\",\"Jung\",\"M\u00e1rcia Ferreira\",\"marciaferreira\",\"mitologia\",\"netuno\",\"planetas\",\"previs\u00f5es\",\"previsoesastrologicas\",\"psicologia\",\"psicologia anal\u00edtica\",\"quatroelementos\",\"saturno\",\"signos\",\"signosdozodiaco\",\"sinastria\",\"sol\",\"transitosastrologicos\"],\"articleSection\":[\"V\u00cdDEOS\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2025-a-conjuncao-saturno-netuno-parte-2\\\/\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2025-a-conjuncao-saturno-netuno-parte-2\\\/\",\"name\":\"2025 - A CONJUN\u00c7\u00c3O SATURNO NETUNO - PARTE 2 - C.E.A.P.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2025-a-conjuncao-saturno-netuno-parte-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2025-a-conjuncao-saturno-netuno-parte-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/img_destacada.png\",\"datePublished\":\"2025-01-06T20:55:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2025-a-conjuncao-saturno-netuno-parte-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2025-a-conjuncao-saturno-netuno-parte-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2025-a-conjuncao-saturno-netuno-parte-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/img_destacada.png\",\"contentUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/img_destacada.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2025-a-conjuncao-saturno-netuno-parte-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2025 &#8211; A CONJUN\u00c7\u00c3O SATURNO NETUNO &#8211; PARTE 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"name\":\"C.E.A.P.\",\"description\":\"Centro de Estudos de Astrologia Psicol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\",\"name\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"contentUrl\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"width\":140,\"height\":174,\"caption\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/astroceap\\\/\",\"https:\\\/\\\/x.com\\\/astrologiaceap\",\"https:\\\/\\\/www.instagram.com\\\/ceap.astrologia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDsKeXx5S7f2xoPUxNpARSQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/ddb041600c30d210efaa7d497809f126\",\"name\":\"Henrique\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g\",\"caption\":\"Henrique\"},\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/author\\\/henrique\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2025 - A CONJUN\u00c7\u00c3O SATURNO NETUNO - PARTE 2 - C.E.A.P.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"2025 - A CONJUN\u00c7\u00c3O SATURNO NETUNO - PARTE 2 - C.E.A.P.","og_description":"&nbsp; Nessa sequ\u00eancia de v\u00eddeos sobre 2025 estamos compreendendo tudo o diz respeito \u00e0 conjun\u00e7\u00e3o Saturno Netuno, que juntamente com Plut\u00e3o em Aqu\u00e1rio, \u00e9 o grande impacto desta d\u00e9cada. Neste v\u00eddeo, a parte 2 do sequencial de 5 v\u00eddeos, veremo","og_url":"https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/","og_site_name":"C.E.A.P.","article_publisher":"https:\/\/www.facebook.com\/astroceap\/","article_published_time":"2025-01-06T20:55:45+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/01\/img_destacada.png","type":"image\/png"}],"author":"Henrique","twitter_card":"summary_large_image","twitter_creator":"@astrologiaceap","twitter_site":"@astrologiaceap","twitter_misc":{"Escrito por":"Henrique","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/#article","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/"},"author":{"name":"Henrique","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/ddb041600c30d210efaa7d497809f126"},"headline":"2025 &#8211; A CONJUN\u00c7\u00c3O SATURNO NETUNO &#8211; PARTE 2","datePublished":"2025-01-06T20:55:45+00:00","mainEntityOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/"},"wordCount":83,"publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/01\/img_destacada.png","keywords":["#cursodeastrologia","#cursosdeastrologia","#zod\u00edaco","2025","ascendente","astrologia","astrologiapsicologica","autoconhecimento","direcionamento de vida","formacaoemastrologia","hor\u00f3scopo","Jung","M\u00e1rcia Ferreira","marciaferreira","mitologia","netuno","planetas","previs\u00f5es","previsoesastrologicas","psicologia","psicologia anal\u00edtica","quatroelementos","saturno","signos","signosdozodiaco","sinastria","sol","transitosastrologicos"],"articleSection":["V\u00cdDEOS"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/","url":"https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/","name":"2025 - A CONJUN\u00c7\u00c3O SATURNO NETUNO - PARTE 2 - C.E.A.P.","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/#primaryimage"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/01\/img_destacada.png","datePublished":"2025-01-06T20:55:45+00:00","breadcrumb":{"@id":"https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/#primaryimage","url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/01\/img_destacada.png","contentUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/01\/img_destacada.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/astroceap.com.br\/ceap\/2025-a-conjuncao-saturno-netuno-parte-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/astroceap.com.br\/ceap\/"},{"@type":"ListItem","position":2,"name":"2025 &#8211; A CONJUN\u00c7\u00c3O SATURNO NETUNO &#8211; PARTE 2"}]},{"@type":"WebSite","@id":"https:\/\/astroceap.com.br\/ceap\/#website","url":"https:\/\/astroceap.com.br\/ceap\/","name":"C.E.A.P.","description":"Centro de Estudos de Astrologia Psicol\u00f3gica","publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astroceap.com.br\/ceap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/astroceap.com.br\/ceap\/#organization","name":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica","url":"https:\/\/astroceap.com.br\/ceap\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/","url":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","contentUrl":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","width":140,"height":174,"caption":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/astroceap\/","https:\/\/x.com\/astrologiaceap","https:\/\/www.instagram.com\/ceap.astrologia\/","https:\/\/www.youtube.com\/channel\/UCDsKeXx5S7f2xoPUxNpARSQ"]},{"@type":"Person","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/ddb041600c30d210efaa7d497809f126","name":"Henrique","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g","caption":"Henrique"},"url":"https:\/\/astroceap.com.br\/ceap\/author\/henrique\/"}]}},"_links":{"self":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/11003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/comments?post=11003"}],"version-history":[{"count":1,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/11003\/revisions"}],"predecessor-version":[{"id":11005,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/11003\/revisions\/11005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media\/11004"}],"wp:attachment":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media?parent=11003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/categories?post=11003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/tags?post=11003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}