{"id":11278,"date":"2025-07-23T17:12:06","date_gmt":"2025-07-23T20:12:06","guid":{"rendered":"https:\/\/astroceap.com.br\/ceap\/?p=11278"},"modified":"2025-07-29T22:52:10","modified_gmt":"2025-07-30T01:52:10","slug":"evento-noite-astrologica-e-workshop-astrologia-e-sonhos","status":"publish","type":"post","link":"https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/","title":{"rendered":"Evento &#8220;Noite Astrol\u00f3gica&#8221; e workshop &#8220;Astrologia e Sonhos&#8221;"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #000000;\">E foi assim&#8230; cenas do evento &#8220;Noite Astrol\u00f3gica&#8221; e do workshop &#8220;Astrologia e Sonhos&#8221;, re-inaugurando o formato presencial no C.E.A.P em Sousas, Campinas\/SP<\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-11279 lazyload\" data-src=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/06_evento-300x300.png\" alt=\"\" width=\"300\" height=\"300\" data-srcset=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/06_evento-300x300.png 300w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/06_evento-1024x1024.png 1024w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/06_evento-150x150.png 150w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/06_evento-768x768.png 768w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/06_evento-230x230.png 230w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/06_evento-330x330.png 330w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/06_evento.png 1080w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/> \u00a0<img decoding=\"async\" class=\"alignnone size-medium wp-image-11281 lazyload\" data-src=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/01_evento-300x300.png\" alt=\"\" width=\"300\" height=\"300\" data-srcset=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/01_evento-300x300.png 300w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/01_evento-1024x1024.png 1024w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/01_evento-150x150.png 150w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/01_evento-768x768.png 768w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/01_evento-230x230.png 230w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/01_evento-330x330.png 330w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/01_evento.png 1080w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/> \u00a0<img decoding=\"async\" class=\"alignnone size-medium wp-image-11283 lazyload\" data-src=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/02_evento-300x300.png\" alt=\"\" width=\"300\" height=\"300\" data-srcset=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/02_evento-300x300.png 300w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/02_evento-1024x1024.png 1024w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/02_evento-150x150.png 150w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/02_evento-768x768.png 768w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/02_evento-230x230.png 230w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/02_evento-330x330.png 330w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/02_evento.png 1080w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/> \u00a0<img decoding=\"async\" class=\"alignnone size-medium wp-image-11285 lazyload\" data-src=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/03_evento-300x300.png\" alt=\"\" width=\"300\" height=\"300\" data-srcset=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/03_evento-300x300.png 300w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/03_evento-1024x1024.png 1024w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/03_evento-150x150.png 150w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/03_evento-768x768.png 768w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/03_evento-230x230.png 230w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/03_evento-330x330.png 330w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/03_evento.png 1080w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/> \u00a0<img decoding=\"async\" class=\"alignnone size-medium wp-image-11287 lazyload\" data-src=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/04_evento-300x300.png\" alt=\"\" width=\"300\" height=\"300\" data-srcset=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/04_evento-300x300.png 300w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/04_evento-1024x1024.png 1024w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/04_evento-150x150.png 150w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/04_evento-768x768.png 768w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/04_evento-230x230.png 230w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/04_evento-330x330.png 330w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/04_evento.png 1080w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/> \u00a0<img decoding=\"async\" class=\"alignnone size-medium wp-image-11289 lazyload\" data-src=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/05_evento-300x300.png\" alt=\"\" width=\"300\" height=\"300\" data-srcset=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/05_evento-300x300.png 300w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/05_evento-1024x1024.png 1024w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/05_evento-150x150.png 150w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/05_evento-768x768.png 768w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/05_evento-230x230.png 230w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/05_evento-330x330.png 330w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/05_evento.png 1080w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E foi assim&#8230; cenas do evento &#8220;Noite Astrol\u00f3gica&#8221; e do workshop &#8220;Astrologia e Sonhos&#8221;, re-inaugurando o formato presencial no C.E.A.P em Sousas, Campinas\/SP \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n","protected":false},"author":8,"featured_media":11289,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[31,27],"tags":[115,114,110,133,37,136,74,396,338,198,194,280,44,72,246,268,40,43,520,158,134,38,46,135,42,294,142,181,141,519],"class_list":["post-11278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-eventos-anteriores","tag-cursodeastrologia","tag-cursosdeastrologia","tag-zodiaco","tag-ascendente","tag-astrologia","tag-astrologiapsicologica","tag-autoconhecimento","tag-campinas","tag-direcionamento-de-vida","tag-evento","tag-evento-presencial","tag-formacaoemastrologia","tag-horoscopo","tag-jung","tag-marcia-ferreira","tag-marciaferreira","tag-mitologia","tag-planetas","tag-presencial","tag-previsoes","tag-previsoesastrologicas","tag-psicologia","tag-psicologia-analitica","tag-quatroelementos","tag-signos","tag-signosdozodiaco","tag-sinastria","tag-sol","tag-transitosastrologicos","tag-workshop"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evento &quot;Noite Astrol\u00f3gica&quot; e workshop &quot;Astrologia e Sonhos&quot; - C.E.A.P.<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evento &quot;Noite Astrol\u00f3gica&quot; e workshop &quot;Astrologia e Sonhos&quot; - C.E.A.P.\" \/>\n<meta property=\"og:description\" content=\"E foi assim&#8230; cenas do evento &#8220;Noite Astrol\u00f3gica&#8221; e do workshop &#8220;Astrologia e Sonhos&#8221;, re-inaugurando o formato presencial no C.E.A.P em Sousas, Campinas\/SP \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/\" \/>\n<meta property=\"og:site_name\" content=\"C.E.A.P.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/astroceap\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-23T20:12:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T01:52:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/05_evento.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Henrique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:site\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Henrique\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\\\/\"},\"author\":{\"name\":\"Henrique\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/ddb041600c30d210efaa7d497809f126\"},\"headline\":\"Evento &#8220;Noite Astrol\u00f3gica&#8221; e workshop &#8220;Astrologia e Sonhos&#8221;\",\"datePublished\":\"2025-07-23T20:12:06+00:00\",\"dateModified\":\"2025-07-30T01:52:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\\\/\"},\"wordCount\":37,\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/05_evento.png\",\"keywords\":[\"#cursodeastrologia\",\"#cursosdeastrologia\",\"#zod\u00edaco\",\"ascendente\",\"astrologia\",\"astrologiapsicologica\",\"autoconhecimento\",\"campinas\",\"direcionamento de vida\",\"evento\",\"evento presencial\",\"formacaoemastrologia\",\"hor\u00f3scopo\",\"Jung\",\"M\u00e1rcia Ferreira\",\"marciaferreira\",\"mitologia\",\"planetas\",\"presencial\",\"previs\u00f5es\",\"previsoesastrologicas\",\"psicologia\",\"psicologia anal\u00edtica\",\"quatroelementos\",\"signos\",\"signosdozodiaco\",\"sinastria\",\"sol\",\"transitosastrologicos\",\"workshop\"],\"articleSection\":[\"EVENTOS\",\"EVENTOS ANTERIORES\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\\\/\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\\\/\",\"name\":\"Evento \\\"Noite Astrol\u00f3gica\\\" e workshop \\\"Astrologia e Sonhos\\\" - C.E.A.P.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/05_evento.png\",\"datePublished\":\"2025-07-23T20:12:06+00:00\",\"dateModified\":\"2025-07-30T01:52:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/05_evento.png\",\"contentUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/05_evento.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evento &#8220;Noite Astrol\u00f3gica&#8221; e workshop &#8220;Astrologia e Sonhos&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"name\":\"C.E.A.P.\",\"description\":\"Centro de Estudos de Astrologia Psicol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\",\"name\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"contentUrl\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"width\":140,\"height\":174,\"caption\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/astroceap\\\/\",\"https:\\\/\\\/x.com\\\/astrologiaceap\",\"https:\\\/\\\/www.instagram.com\\\/ceap.astrologia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDsKeXx5S7f2xoPUxNpARSQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/ddb041600c30d210efaa7d497809f126\",\"name\":\"Henrique\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g\",\"caption\":\"Henrique\"},\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/author\\\/henrique\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evento \"Noite Astrol\u00f3gica\" e workshop \"Astrologia e Sonhos\" - C.E.A.P.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"Evento \"Noite Astrol\u00f3gica\" e workshop \"Astrologia e Sonhos\" - C.E.A.P.","og_description":"E foi assim&#8230; cenas do evento &#8220;Noite Astrol\u00f3gica&#8221; e do workshop &#8220;Astrologia e Sonhos&#8221;, re-inaugurando o formato presencial no C.E.A.P em Sousas, Campinas\/SP \u00a0 \u00a0 \u00a0 \u00a0 \u00a0","og_url":"https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/","og_site_name":"C.E.A.P.","article_publisher":"https:\/\/www.facebook.com\/astroceap\/","article_published_time":"2025-07-23T20:12:06+00:00","article_modified_time":"2025-07-30T01:52:10+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/05_evento.png","type":"image\/png"}],"author":"Henrique","twitter_card":"summary_large_image","twitter_creator":"@astrologiaceap","twitter_site":"@astrologiaceap","twitter_misc":{"Escrito por":"Henrique","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/#article","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/"},"author":{"name":"Henrique","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/ddb041600c30d210efaa7d497809f126"},"headline":"Evento &#8220;Noite Astrol\u00f3gica&#8221; e workshop &#8220;Astrologia e Sonhos&#8221;","datePublished":"2025-07-23T20:12:06+00:00","dateModified":"2025-07-30T01:52:10+00:00","mainEntityOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/"},"wordCount":37,"publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/05_evento.png","keywords":["#cursodeastrologia","#cursosdeastrologia","#zod\u00edaco","ascendente","astrologia","astrologiapsicologica","autoconhecimento","campinas","direcionamento de vida","evento","evento presencial","formacaoemastrologia","hor\u00f3scopo","Jung","M\u00e1rcia Ferreira","marciaferreira","mitologia","planetas","presencial","previs\u00f5es","previsoesastrologicas","psicologia","psicologia anal\u00edtica","quatroelementos","signos","signosdozodiaco","sinastria","sol","transitosastrologicos","workshop"],"articleSection":["EVENTOS","EVENTOS ANTERIORES"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/","url":"https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/","name":"Evento \"Noite Astrol\u00f3gica\" e workshop \"Astrologia e Sonhos\" - C.E.A.P.","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/#primaryimage"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/05_evento.png","datePublished":"2025-07-23T20:12:06+00:00","dateModified":"2025-07-30T01:52:10+00:00","breadcrumb":{"@id":"https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/#primaryimage","url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/05_evento.png","contentUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/05_evento.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/astroceap.com.br\/ceap\/evento-noite-astrologica-e-workshop-astrologia-e-sonhos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/astroceap.com.br\/ceap\/"},{"@type":"ListItem","position":2,"name":"Evento &#8220;Noite Astrol\u00f3gica&#8221; e workshop &#8220;Astrologia e Sonhos&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/astroceap.com.br\/ceap\/#website","url":"https:\/\/astroceap.com.br\/ceap\/","name":"C.E.A.P.","description":"Centro de Estudos de Astrologia Psicol\u00f3gica","publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astroceap.com.br\/ceap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/astroceap.com.br\/ceap\/#organization","name":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica","url":"https:\/\/astroceap.com.br\/ceap\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/","url":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","contentUrl":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","width":140,"height":174,"caption":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/astroceap\/","https:\/\/x.com\/astrologiaceap","https:\/\/www.instagram.com\/ceap.astrologia\/","https:\/\/www.youtube.com\/channel\/UCDsKeXx5S7f2xoPUxNpARSQ"]},{"@type":"Person","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/ddb041600c30d210efaa7d497809f126","name":"Henrique","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g","caption":"Henrique"},"url":"https:\/\/astroceap.com.br\/ceap\/author\/henrique\/"}]}},"_links":{"self":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/11278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/comments?post=11278"}],"version-history":[{"count":4,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/11278\/revisions"}],"predecessor-version":[{"id":11315,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/11278\/revisions\/11315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media\/11289"}],"wp:attachment":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media?parent=11278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/categories?post=11278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/tags?post=11278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}