{"id":11293,"date":"2025-07-21T18:21:06","date_gmt":"2025-07-21T21:21:06","guid":{"rendered":"https:\/\/astroceap.com.br\/ceap\/?p=11293"},"modified":"2025-07-23T18:30:49","modified_gmt":"2025-07-23T21:30:49","slug":"como-eu-comecei-na-astrologia","status":"publish","type":"post","link":"https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/","title":{"rendered":"COMO EU COMECEI NA ASTROLOGIA"},"content":{"rendered":"<p style=\"text-align: center;\"><iframe title=\"como_comecei\" data-src=\"https:\/\/player.vimeo.com\/video\/1103932708?badge=0&amp;autopause=0&amp;player_id=0&amp;app_id=58479\" width=\"360\" height=\"640\" frameborder=\"0\" src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<div class=\"xdj266r x14z9mp xat24cr x1lziwak x1vvkbs x126k92a\">\n<div dir=\"auto\"><span style=\"color: #000000;\">Conta aqui pra gente como \u00e9 o teu contato com a Astrologia! Nenhum? D\u00favidas? Ama, adora? N\u00e3o gosta?<\/span><\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><span style=\"color: #000000;\">Estou compartilhando um pouco da minha pr\u00f3pria experi\u00eancia e l\u00e1 se v\u00e3o 30 anos&#8230;mas agora queria ouvir de vc, pq sempre me identifico com esses depoimentos.<\/span><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Conta aqui pra gente como \u00e9 o teu contato com a Astrologia! Nenhum? D\u00favidas? Ama, adora? N\u00e3o gosta? Estou compartilhando um pouco da minha pr\u00f3pria experi\u00eancia e l\u00e1 se v\u00e3o 30 anos&#8230;mas agora queria ouvir de vc, pq sempre me<\/p>\n","protected":false},"author":8,"featured_media":11294,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[180],"tags":[115,114,110,133,37,136,74,326,338,280,44,521,72,246,268,40,43,158,134,38,46,135,42,294,142,181,141],"class_list":["post-11293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videos","tag-cursodeastrologia","tag-cursosdeastrologia","tag-zodiaco","tag-ascendente","tag-astrologia","tag-astrologiapsicologica","tag-autoconhecimento","tag-comeco","tag-direcionamento-de-vida","tag-formacaoemastrologia","tag-horoscopo","tag-inicio","tag-jung","tag-marcia-ferreira","tag-marciaferreira","tag-mitologia","tag-planetas","tag-previsoes","tag-previsoesastrologicas","tag-psicologia","tag-psicologia-analitica","tag-quatroelementos","tag-signos","tag-signosdozodiaco","tag-sinastria","tag-sol","tag-transitosastrologicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMO EU COMECEI NA ASTROLOGIA - C.E.A.P.<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMO EU COMECEI NA ASTROLOGIA - C.E.A.P.\" \/>\n<meta property=\"og:description\" content=\"Conta aqui pra gente como \u00e9 o teu contato com a Astrologia! Nenhum? D\u00favidas? Ama, adora? N\u00e3o gosta? Estou compartilhando um pouco da minha pr\u00f3pria experi\u00eancia e l\u00e1 se v\u00e3o 30 anos&#8230;mas agora queria ouvir de vc, pq sempre me\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/\" \/>\n<meta property=\"og:site_name\" content=\"C.E.A.P.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/astroceap\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-21T21:21:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-23T21:30:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/IMG_DESTACADA-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Henrique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:site\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Henrique\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/como-eu-comecei-na-astrologia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/como-eu-comecei-na-astrologia\\\/\"},\"author\":{\"name\":\"Henrique\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/ddb041600c30d210efaa7d497809f126\"},\"headline\":\"COMO EU COMECEI NA ASTROLOGIA\",\"datePublished\":\"2025-07-21T21:21:06+00:00\",\"dateModified\":\"2025-07-23T21:30:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/como-eu-comecei-na-astrologia\\\/\"},\"wordCount\":53,\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/como-eu-comecei-na-astrologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/IMG_DESTACADA-1.png\",\"keywords\":[\"#cursodeastrologia\",\"#cursosdeastrologia\",\"#zod\u00edaco\",\"ascendente\",\"astrologia\",\"astrologiapsicologica\",\"autoconhecimento\",\"come\u00e7o\",\"direcionamento de vida\",\"formacaoemastrologia\",\"hor\u00f3scopo\",\"inicio\",\"Jung\",\"M\u00e1rcia Ferreira\",\"marciaferreira\",\"mitologia\",\"planetas\",\"previs\u00f5es\",\"previsoesastrologicas\",\"psicologia\",\"psicologia anal\u00edtica\",\"quatroelementos\",\"signos\",\"signosdozodiaco\",\"sinastria\",\"sol\",\"transitosastrologicos\"],\"articleSection\":[\"V\u00cdDEOS\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/como-eu-comecei-na-astrologia\\\/\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/como-eu-comecei-na-astrologia\\\/\",\"name\":\"COMO EU COMECEI NA ASTROLOGIA - C.E.A.P.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/como-eu-comecei-na-astrologia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/como-eu-comecei-na-astrologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/IMG_DESTACADA-1.png\",\"datePublished\":\"2025-07-21T21:21:06+00:00\",\"dateModified\":\"2025-07-23T21:30:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/como-eu-comecei-na-astrologia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/como-eu-comecei-na-astrologia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/como-eu-comecei-na-astrologia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/IMG_DESTACADA-1.png\",\"contentUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/IMG_DESTACADA-1.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/como-eu-comecei-na-astrologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMO EU COMECEI NA ASTROLOGIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"name\":\"C.E.A.P.\",\"description\":\"Centro de Estudos de Astrologia Psicol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\",\"name\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"contentUrl\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"width\":140,\"height\":174,\"caption\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/astroceap\\\/\",\"https:\\\/\\\/x.com\\\/astrologiaceap\",\"https:\\\/\\\/www.instagram.com\\\/ceap.astrologia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDsKeXx5S7f2xoPUxNpARSQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/ddb041600c30d210efaa7d497809f126\",\"name\":\"Henrique\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g\",\"caption\":\"Henrique\"},\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/author\\\/henrique\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMO EU COMECEI NA ASTROLOGIA - C.E.A.P.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"COMO EU COMECEI NA ASTROLOGIA - C.E.A.P.","og_description":"Conta aqui pra gente como \u00e9 o teu contato com a Astrologia! Nenhum? D\u00favidas? Ama, adora? N\u00e3o gosta? Estou compartilhando um pouco da minha pr\u00f3pria experi\u00eancia e l\u00e1 se v\u00e3o 30 anos&#8230;mas agora queria ouvir de vc, pq sempre me","og_url":"https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/","og_site_name":"C.E.A.P.","article_publisher":"https:\/\/www.facebook.com\/astroceap\/","article_published_time":"2025-07-21T21:21:06+00:00","article_modified_time":"2025-07-23T21:30:49+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/IMG_DESTACADA-1.png","type":"image\/png"}],"author":"Henrique","twitter_card":"summary_large_image","twitter_creator":"@astrologiaceap","twitter_site":"@astrologiaceap","twitter_misc":{"Escrito por":"Henrique","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/#article","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/"},"author":{"name":"Henrique","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/ddb041600c30d210efaa7d497809f126"},"headline":"COMO EU COMECEI NA ASTROLOGIA","datePublished":"2025-07-21T21:21:06+00:00","dateModified":"2025-07-23T21:30:49+00:00","mainEntityOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/"},"wordCount":53,"publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/IMG_DESTACADA-1.png","keywords":["#cursodeastrologia","#cursosdeastrologia","#zod\u00edaco","ascendente","astrologia","astrologiapsicologica","autoconhecimento","come\u00e7o","direcionamento de vida","formacaoemastrologia","hor\u00f3scopo","inicio","Jung","M\u00e1rcia Ferreira","marciaferreira","mitologia","planetas","previs\u00f5es","previsoesastrologicas","psicologia","psicologia anal\u00edtica","quatroelementos","signos","signosdozodiaco","sinastria","sol","transitosastrologicos"],"articleSection":["V\u00cdDEOS"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/","url":"https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/","name":"COMO EU COMECEI NA ASTROLOGIA - C.E.A.P.","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/#primaryimage"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/IMG_DESTACADA-1.png","datePublished":"2025-07-21T21:21:06+00:00","dateModified":"2025-07-23T21:30:49+00:00","breadcrumb":{"@id":"https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/#primaryimage","url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/IMG_DESTACADA-1.png","contentUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2025\/07\/IMG_DESTACADA-1.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/astroceap.com.br\/ceap\/como-eu-comecei-na-astrologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/astroceap.com.br\/ceap\/"},{"@type":"ListItem","position":2,"name":"COMO EU COMECEI NA ASTROLOGIA"}]},{"@type":"WebSite","@id":"https:\/\/astroceap.com.br\/ceap\/#website","url":"https:\/\/astroceap.com.br\/ceap\/","name":"C.E.A.P.","description":"Centro de Estudos de Astrologia Psicol\u00f3gica","publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astroceap.com.br\/ceap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/astroceap.com.br\/ceap\/#organization","name":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica","url":"https:\/\/astroceap.com.br\/ceap\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/","url":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","contentUrl":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","width":140,"height":174,"caption":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/astroceap\/","https:\/\/x.com\/astrologiaceap","https:\/\/www.instagram.com\/ceap.astrologia\/","https:\/\/www.youtube.com\/channel\/UCDsKeXx5S7f2xoPUxNpARSQ"]},{"@type":"Person","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/ddb041600c30d210efaa7d497809f126","name":"Henrique","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f67b5096b21338217745cd48509810b134c96a04c20b3b2ebf14d0f43eaaab5b?s=96&d=blank&r=g","caption":"Henrique"},"url":"https:\/\/astroceap.com.br\/ceap\/author\/henrique\/"}]}},"_links":{"self":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/11293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/comments?post=11293"}],"version-history":[{"count":3,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/11293\/revisions"}],"predecessor-version":[{"id":11297,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/11293\/revisions\/11297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media\/11294"}],"wp:attachment":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media?parent=11293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/categories?post=11293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/tags?post=11293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}