{"id":714,"date":"2017-12-13T12:04:43","date_gmt":"2017-12-13T14:04:43","guid":{"rendered":"http:\/\/astroceap.com.br\/ceap\/?p=714"},"modified":"2017-12-13T12:04:43","modified_gmt":"2017-12-13T14:04:43","slug":"astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos","status":"publish","type":"post","link":"https:\/\/astroceap.com.br\/ceap\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\/","title":{"rendered":"ASTROLOGIA K\u00c1RMICA OU N\u00d3S QUE AQUI ESTAMOS POR TI ESPERAMOS"},"content":{"rendered":"<h4><span style=\"color: #993300;\">por Anna Maria Costa Ribeiro<\/span><\/h4>\n<p><span lang=\"pt-BR\">Quando dei uma palestra no evento da Gaia em jul\/11 vi um\u00a0 excelente e tenebroso filme document\u00e1rio com o t\u00edtulo mort\u00edfero acima. Gostei. Eis uma s\u00edntese da minha palestra:<\/p>\n<p>Os objetivos da Astrologia Karmica s\u00e3o:<\/p>\n<p>1. Curr\u00edculo c\u00f3smico:<br \/>\nA sua vida meu bem, \u00e9 como um livro. Hoje v. est\u00e1 no cap\u00edtulo 1001, as Vidas Passadas\/VP s\u00e3o os cap\u00edtulos anteriores e as Vidas Futuras s\u00e3o os seguintes. V. pode programar sua vida futura, como eu j\u00e1 fiz e n\u00e3o vou dizer. Comece desde hoje se movimentando para o tal futuro. Assim, se v. quer ser um viajante , comece a ver o NatGeo, a atravessar a barca para Niteroi, dar uma passadinha na cidade mais pr\u00f3xima, ler sobre outros locais,etc.<\/p>\n<p>Reencarnar \u00e9 retornar com uma meta.<\/p>\n<p>O Sol \u00e9 o seu lado heroico, capaz de mi-la-gres. O seu filme, enredo, sua l\u00f3gica pessoal, seu caminho.<\/p>\n<p>A Lua \u00e9 seu lado mais verdadeiro e profundo. Ela n\u00e3o \u00e9 fantasia, \u00e9 uma realidade e car~encia &#8211; jamais suprida, por mais que fa\u00e7a ou tenha. \u00c9 o que move o Sol.<\/p>\n<p>Assim, o Sol em Sagitario tem o caminho do n\u00e3o retorno, de ir sem voltar.<br \/>\nA Lua em Capricornio tem a car\u00eancia das realiza\u00e7\u00f5es e constru\u00e7\u00f5es, por mais que j\u00e1 tenha constru\u00eddo. E deve construir s\u00f2zinha, tornando-se, qui\u00e7\u00e1s,inacess\u00edvel<\/p>\n<p>A alma dilacerada,ainda tem essa, \u00e9 quando h\u00e1 um conflito entre a raz\u00e3o, as conven\u00e7\u00f5es socio-culturais, o sistema, a necessidade do pol\u00edticamente correto e os sentimentos, os anseios do cora\u00e7\u00e3o,da alma, do ka, muitas vezes atacadas como transgress\u00f5es.<br \/>\nOs planetas Jupiter,Urano e Plut\u00e3o s\u00e3o os principais transgressores. Querem ir al\u00e9m, transformarem, progredirem, alterar situa\u00e7\u00f5es. Se assim n\u00e3o fizessem, estar\u00edamos na idade da pedra. No entanto, esses transgressores pagam seu pre\u00e7o com aud\u00e1cia.<\/p>\n<p>2. esclarecimento de Quest\u00f5es.<br \/>\nAlgo que hoje est\u00e1 atravessado, que lhe amedronta e ,portanto lhe enfraquece. Se v.tem medo, envelhece mais depressa. E nenhuma pl\u00e1stica resolve.<br \/>\nO que lhe amedronta?<\/p>\n<p>3.Evolu\u00e7\u00e3o.<br \/>\nV.tem um compromisso com a evolu\u00e7\u00e3o pessoal. Ou seja, tornar-se naquilo que v. \u00e9, no seu mapa, por direito de nascimento. Esse \u00e9 seu dharma,seu ponto de honra.<br \/>\nSe v.nasceu Libra seu karma \u00e9 de relacionamento, de aceita\u00e7\u00e3o num ambiente, de concilia\u00e7\u00e3o social. Por isso, atrair\u00e1 conflitos, para aplicar a t\u00e9cnica da pacifica\u00e7\u00e3o, fazer concess\u00f5es. Se conceder com raiva, vai se sentir injusti\u00e7ada, acaba ficando agressiva como Aries. Mas como n\u00e3o \u00e9 Aries, atrai diabetes ,panc reatite,etc. Portanto, Libra deve conceder sem raiva, reconhecendo seus desafios de vida. S\u00f3 assim se TORNA Libra.<\/p>\n<p>Outras quest\u00f5es de evolu\u00e7\u00e3o devem-se ao envenenamento<br \/>\ncertas pessoas envenenam\u00a0 o ambiente, esse \u00e9 seu hobby. O k de Netuno \u00e9 descobrir o envenenador e n\u00e3o lhe dar o menor espa\u00e7o: n\u00e3o d\u00e1 para negociar com envenenador, com o aedes egypcies &#8211; eles jamais se arrependem, n\u00e3o se redimem. Isole quem lhe envenena.<\/p>\n<p>Plut\u00e3o despreza aquilo que n\u00e3o pode ter.N\u00e3o dar aten\u00e7\u00e3o \u00e9 o mesmo que eliminar.Se v.d\u00e1 aten\u00e7\u00e3o ao inimigo, ele se fortalece, ele ganha visibilidade. Pluto tem o desinteresse da superioridade.<\/p>\n<p>Saturno tem o desafio do tempo certo. Se v. mostra que tem pressa, mostra que n\u00e3o tem controle. Sat n\u00e3o pode pular degraus. Tem que farejar as tend\u00eancias do momento e atuar na hora cronometrada.<\/p>\n<p>Jupiter faz as conquistas parecerem f\u00e1ceis, ainda que n\u00e3o sejam.Dissimula o esfor\u00e7o, sabe que se outros pensarem que\u00a0 v.teve que se esfor\u00e7ar, dedicar-se demais, \u00e9 porque tal-vez n\u00e3o seja competente. A\u00ed \u00eale diz: Fiz com um p\u00e9 nas costas.<\/p>\n<p>4.Aprender a receber quem v.ama, reverenciar o amado\/a, pois isso est\u00e1 enfeitando a sua vida, ornamentando-a, fazendo-a florescer. Fa\u00e7a o outro se sentir benvindo. O objeto de a,or de Venus \u00e9 uma d\u00e1diva.Eis que se precisa sentir gratid\u00e3o por tudo que o amor lhe oferece. Se v. n\u00e3o se sente assim por quem pensa que ama, o que est\u00e1 fazendo com essa pessoa?<\/p>\n<p>5. Causas e enredos por tr\u00e1s do seu mapa, os bastidores de sua vida. Algo est\u00e1 lhe empurrando para certas atitudes.<br \/>\nPor tr\u00e1s de Le\u00e3o est\u00e1 o desejo de ser visto, de ser respeitado.<br \/>\nO que est\u00e1 por tr\u00e1s do descompromisso? A autonomia de Urano pode ser o medo de perder seu poder e seu espa\u00e7o, de ser possu\u00eddo por algu\u00e9m. Aquarios s\u00e3o com os arcanjos; distanciados.<\/p>\n<p>6.Previs\u00f5es<br \/>\nA s regress\u00f5es de VP servem para ajudar a decidir situa\u00e7\u00f5es atuais, esclarece-las e mostrar o que vai lhe acontecer no futuro se v. n\u00e3o mudar. Se o que v. reconhece numa VP \u00e9 legal, n\u00e3o mude, meu bem, n\u00e3o mude, pois aquilo vai se repetir again. Se n\u00e3o gostou duma VP, corrrrra e mude para evitar a repeti\u00e7\u00e3o, again.<br \/>\nVP funcionam com um futuro breve.Olha que eu j\u00e1 fiz mais de 9.000 regress\u00f5es com clientes e tem estat[istica pr\u00e1 caramba.<\/p>\n<p>E mais n\u00e3o digo, porque tenho outras coisas para fazer. <\/span>Tchau.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #800000;\"><span lang=\"pt-BR\">Curr\u00edculo:<\/span><\/span><\/strong><span lang=\"pt-BR\"> Diretora da URANTIAM. Professora, consultora, escritora com 17 livros .Atuando tempo integral desde 1980 como astr\u00f3loga, numer\u00f3loga, tar\u00f3loga, uf\u00f3loga, facilitadora em Vidas Passadas e Constela\u00e7\u00e3o Familiar. Tamb\u00e9m\u00a0 d\u00e1 cursos de Mitologia grega, sum\u00e9ria e orixas e de cabala.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>por Anna Maria Costa Ribeiro Quando dei uma palestra no evento da Gaia em jul\/11 vi um\u00a0 excelente e tenebroso filme document\u00e1rio com o t\u00edtulo mort\u00edfero acima. Gostei. Eis uma s\u00edntese da minha palestra: Os objetivos da Astrologia Karmica s\u00e3o:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-714","post","type-post","status-publish","format-standard","hentry","category-artigos-nacionais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASTROLOGIA K\u00c1RMICA OU N\u00d3S QUE AQUI ESTAMOS POR TI ESPERAMOS - C.E.A.P.<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASTROLOGIA K\u00c1RMICA OU N\u00d3S QUE AQUI ESTAMOS POR TI ESPERAMOS - C.E.A.P.\" \/>\n<meta property=\"og:description\" content=\"por Anna Maria Costa Ribeiro Quando dei uma palestra no evento da Gaia em jul\/11 vi um\u00a0 excelente e tenebroso filme document\u00e1rio com o t\u00edtulo mort\u00edfero acima. Gostei. Eis uma s\u00edntese da minha palestra: Os objetivos da Astrologia Karmica s\u00e3o:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astroceap.com.br\/ceap\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\/\" \/>\n<meta property=\"og:site_name\" content=\"C.E.A.P.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/astroceap\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-13T14:04:43+00:00\" \/>\n<meta name=\"author\" content=\"geoadm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:site\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"geoadm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\\\/\"},\"author\":{\"name\":\"geoadm\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/d0e55c0b606b43806744ff7d1d211616\"},\"headline\":\"ASTROLOGIA K\u00c1RMICA OU N\u00d3S QUE AQUI ESTAMOS POR TI ESPERAMOS\",\"datePublished\":\"2017-12-13T14:04:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\\\/\"},\"wordCount\":943,\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"articleSection\":[\"ARTIGOS NACIONAIS\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\\\/\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\\\/\",\"name\":\"ASTROLOGIA K\u00c1RMICA OU N\u00d3S QUE AQUI ESTAMOS POR TI ESPERAMOS - C.E.A.P.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\"},\"datePublished\":\"2017-12-13T14:04:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASTROLOGIA K\u00c1RMICA OU N\u00d3S QUE AQUI ESTAMOS POR TI ESPERAMOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"name\":\"C.E.A.P.\",\"description\":\"Centro de Estudos de Astrologia Psicol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\",\"name\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"contentUrl\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"width\":140,\"height\":174,\"caption\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/astroceap\\\/\",\"https:\\\/\\\/x.com\\\/astrologiaceap\",\"https:\\\/\\\/www.instagram.com\\\/ceap.astrologia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDsKeXx5S7f2xoPUxNpARSQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/d0e55c0b606b43806744ff7d1d211616\",\"name\":\"geoadm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g\",\"caption\":\"geoadm\"},\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/author\\\/geoadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASTROLOGIA K\u00c1RMICA OU N\u00d3S QUE AQUI ESTAMOS POR TI ESPERAMOS - C.E.A.P.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"ASTROLOGIA K\u00c1RMICA OU N\u00d3S QUE AQUI ESTAMOS POR TI ESPERAMOS - C.E.A.P.","og_description":"por Anna Maria Costa Ribeiro Quando dei uma palestra no evento da Gaia em jul\/11 vi um\u00a0 excelente e tenebroso filme document\u00e1rio com o t\u00edtulo mort\u00edfero acima. Gostei. Eis uma s\u00edntese da minha palestra: Os objetivos da Astrologia Karmica s\u00e3o:","og_url":"https:\/\/astroceap.com.br\/ceap\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\/","og_site_name":"C.E.A.P.","article_publisher":"https:\/\/www.facebook.com\/astroceap\/","article_published_time":"2017-12-13T14:04:43+00:00","author":"geoadm","twitter_card":"summary_large_image","twitter_creator":"@astrologiaceap","twitter_site":"@astrologiaceap","twitter_misc":{"Escrito por":"geoadm","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astroceap.com.br\/ceap\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\/#article","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\/"},"author":{"name":"geoadm","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/d0e55c0b606b43806744ff7d1d211616"},"headline":"ASTROLOGIA K\u00c1RMICA OU N\u00d3S QUE AQUI ESTAMOS POR TI ESPERAMOS","datePublished":"2017-12-13T14:04:43+00:00","mainEntityOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\/"},"wordCount":943,"publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"articleSection":["ARTIGOS NACIONAIS"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/astroceap.com.br\/ceap\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\/","url":"https:\/\/astroceap.com.br\/ceap\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\/","name":"ASTROLOGIA K\u00c1RMICA OU N\u00d3S QUE AQUI ESTAMOS POR TI ESPERAMOS - C.E.A.P.","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/#website"},"datePublished":"2017-12-13T14:04:43+00:00","breadcrumb":{"@id":"https:\/\/astroceap.com.br\/ceap\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astroceap.com.br\/ceap\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/astroceap.com.br\/ceap\/astrologia-karmica-ou-nos-que-aqui-estamos-por-ti-esperamos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/astroceap.com.br\/ceap\/"},{"@type":"ListItem","position":2,"name":"ASTROLOGIA K\u00c1RMICA OU N\u00d3S QUE AQUI ESTAMOS POR TI ESPERAMOS"}]},{"@type":"WebSite","@id":"https:\/\/astroceap.com.br\/ceap\/#website","url":"https:\/\/astroceap.com.br\/ceap\/","name":"C.E.A.P.","description":"Centro de Estudos de Astrologia Psicol\u00f3gica","publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astroceap.com.br\/ceap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/astroceap.com.br\/ceap\/#organization","name":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica","url":"https:\/\/astroceap.com.br\/ceap\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/","url":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","contentUrl":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","width":140,"height":174,"caption":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/astroceap\/","https:\/\/x.com\/astrologiaceap","https:\/\/www.instagram.com\/ceap.astrologia\/","https:\/\/www.youtube.com\/channel\/UCDsKeXx5S7f2xoPUxNpARSQ"]},{"@type":"Person","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/d0e55c0b606b43806744ff7d1d211616","name":"geoadm","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g","caption":"geoadm"},"url":"https:\/\/astroceap.com.br\/ceap\/author\/geoadm\/"}]}},"_links":{"self":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/comments?post=714"}],"version-history":[{"count":1,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/714\/revisions"}],"predecessor-version":[{"id":715,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/714\/revisions\/715"}],"wp:attachment":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media?parent=714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/categories?post=714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/tags?post=714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}