{"id":721,"date":"2017-12-13T12:21:36","date_gmt":"2017-12-13T14:21:36","guid":{"rendered":"http:\/\/astroceap.com.br\/ceap\/?p=721"},"modified":"2017-12-13T12:22:54","modified_gmt":"2017-12-13T14:22:54","slug":"as-diversas-realidades-e-a-astrologia","status":"publish","type":"post","link":"https:\/\/astroceap.com.br\/ceap\/as-diversas-realidades-e-a-astrologia\/","title":{"rendered":"As Diversas Realidades e a Astrologia"},"content":{"rendered":"<h4><span style=\"color: #993300;\">por Elizabeth Nakata<\/span><\/h4>\n<p style=\"text-align: left;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 No Castelo de Chambord, no Vale do Loire (Fran\u00e7a), a escada principal foi projetada por Leonardo da Vinci. Uma escada nem sempre \u00e9 apenas uma escada, e essa \u00e9 especial. Ela tem o formato da h\u00e9lice dupla do DNA, e isso significa que tem duas escadas entrela\u00e7adas, duas entradas opostas, e se duas pessoas iniciarem a subida ao mesmo tempo, uma em cada entrada, chegar\u00e3o ao topo sem jamais se encontrar.<\/p>\n<p>Olhando a foto fica mais f\u00e1cil entender o mecanismo. Leonardo da Vinci era um g\u00eanio, um homem com conhecimentos muito al\u00e9m de seu tempo. Mas \u00e9 curioso notar que suas inven\u00e7\u00f5es, vistas hoje em dia, se parecem mais como se um de n\u00f3s retornasse ao passado e, com os materiais rudimentares da \u00e9poca, tentasse construir um helic\u00f3ptero, um submarino ou deixar registrado o conhecimento da cadeia helicoidal do DNA. Pensando assim, Leonardo da Vinci poderia ser um cientista que viveu h\u00e1 muitos anos, ou talvez ainda seja contempor\u00e2neo nosso e tenha descoberto como manipular tempo e espa\u00e7o e nascer no ano de 1452. Isso \u00e9 apenas uma provoca\u00e7\u00e3o. Na verdade quero falar sobre s\u00edmbolos e realidade.<\/p>\n<p>Vivemos num mundo de especializa\u00e7\u00f5es, onde procuramos um ortopedista para cuidar do problema na patela, porque outros ortopedistas se especializaram em cuidar da coluna, por exemplo. A vis\u00e3o \u00e9 fragmentada. Isso se aplica a diversas \u00e1reas de conhecimento, e vemos especialistas em Astrologia Tradicional debatendo com os astr\u00f3logos modernos, estes criticando os astr\u00f3logos psic\u00f3logos, os \u00faltimos torcendo o nariz para os cabalistas e por a\u00ed vai.<\/p>\n<p>Com a entrada de Netuno em Peixes, retorna a possibilidade de podermos enxergar o todo, indiscriminadamente, despidos de pr\u00e9-conceitos. A beleza da escada de Da Vinci s\u00f3 pode ser vista e entendida quando nos afastamos um pouco para poder ver o conjunto. Caminhando nela temos apenas metade da vis\u00e3o. Simbolicamente essa \u00e9 nossa realidade, com o conhecimento fragmentado e pulverizado por diversas culturas. Cada uma foi seguindo acreditando deter a verdade absoluta, subindo por um dos lados da escada e, efetivamente, chegando ao topo. Quem escolheu subir pelo outro lado, da mesma forma chegou ao topo. Essas pessoas s\u00e3o conhecedoras profundas do caminho que trilharam, mas n\u00e3o entenderam o mecanismo todo, n\u00e3o detiveram o conhecimento do mecanismo da escada dupla. Para entender o todo, h\u00e1 a necessidade de usar a mente (Netuno em Aqu\u00e1rio, elemento Ar, coletivo), absorver todo o conhecimento produzido at\u00e9 ent\u00e3o, afastar-se das fac\u00e7\u00f5es e pequenas verdades (ou verdades relativas), para adquirir a sabedoria. Com a humildade de quem nasce e precisa aprender com tudo e todos, sem barreiras, sem divis\u00f5es e com a mente aberta para ver que a escada de Da Vinci \u00e9, na verdade, composta de duas, um conjunto que s\u00f3 funciona e existe quando percorrida pelos dois lados.<\/p>\n<p>Quando estudamos diversos m\u00e9todos, abordagens, escolas e estilos, sempre vamos encontrar uma identidade. Astrologia Cabal\u00edstica, Cl\u00e1ssica, Moderna, Psicol\u00f3gica ou qualquer outra abordagem que exista s\u00e3o complementares, jamais excludentes. A beleza est\u00e1 em ver que, como diziam Ouspensky e Gurdjieff, foi fragmentada mas, acredito, com Netuno em Peixes, os fragmentos pouco a pouco come\u00e7am a se reunir, como um grande puzzle, e fazem<\/p>\n<p>todo sentido. Caminhamos para um ponto comum, n\u00e3o h\u00e1 volta, e \u00e9 poss\u00edvel ver que as escolas inici\u00e1ticas e herm\u00e9ticas abrem suas portas e bibliotecas. As diversas escadas s\u00e3o uma s\u00f3, partindo de um mesmo ponto e chegando ao mesmo lugar. As diversas astrologias, religi\u00f5es, seitas, escolas inici\u00e1ticas, ordens e or\u00e1culos respondem \u00e0s mesmas perguntas com respostas iguais. Netuno retorna ao lar e n\u00f3s, mortais, podemos ver que o deus est\u00e1 em sua casa, que engloba toda a \u00e1gua do planeta, nossos corpos que s\u00e3o compostos por cerca de 70% dela, por toda a \u00e1gua simb\u00f3lica da emo\u00e7\u00e3o, compaix\u00e3o e uni\u00e3o.<\/p>\n<p>Elizabeth Nakata<br \/>\nwww.elizabethnakata.com.br<\/p>\n<p>Elizabeth Nakata<\/p>\n<p>Astr\u00f3loga e jornalista. Professora da Escola Regulus, consultora e palestrante. Licenciada junto \u00e0 AstroBrasil e membro da CNA \u2022 Central Nacional de Astrologia. Atua em Astrologia Pessoal, Infantil, Vocacional, Sinastria, Previs\u00f5es, Empresarial e Eletiva e tamb\u00e9m com Mesa Radi\u00f4nica. Escreve para diversos sites e revistas.<br \/>\nwww.elizabethnakata.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>por Elizabeth Nakata \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 No Castelo de Chambord, no Vale do Loire (Fran\u00e7a), a escada principal foi projetada por Leonardo da Vinci. Uma escada nem sempre \u00e9 apenas uma escada, e essa \u00e9 especial. Ela tem o formato da h\u00e9lice<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-721","post","type-post","status-publish","format-standard","hentry","category-artigos-nacionais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>As Diversas Realidades e a Astrologia - C.E.A.P.<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As Diversas Realidades e a Astrologia - C.E.A.P.\" \/>\n<meta property=\"og:description\" content=\"por Elizabeth Nakata \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 No Castelo de Chambord, no Vale do Loire (Fran\u00e7a), a escada principal foi projetada por Leonardo da Vinci. Uma escada nem sempre \u00e9 apenas uma escada, e essa \u00e9 especial. Ela tem o formato da h\u00e9lice\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astroceap.com.br\/ceap\/as-diversas-realidades-e-a-astrologia\/\" \/>\n<meta property=\"og:site_name\" content=\"C.E.A.P.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/astroceap\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-13T14:21:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-13T14:22:54+00:00\" \/>\n<meta name=\"author\" content=\"geoadm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:site\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"geoadm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/as-diversas-realidades-e-a-astrologia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/as-diversas-realidades-e-a-astrologia\\\/\"},\"author\":{\"name\":\"geoadm\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/d0e55c0b606b43806744ff7d1d211616\"},\"headline\":\"As Diversas Realidades e a Astrologia\",\"datePublished\":\"2017-12-13T14:21:36+00:00\",\"dateModified\":\"2017-12-13T14:22:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/as-diversas-realidades-e-a-astrologia\\\/\"},\"wordCount\":726,\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"articleSection\":[\"ARTIGOS NACIONAIS\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/as-diversas-realidades-e-a-astrologia\\\/\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/as-diversas-realidades-e-a-astrologia\\\/\",\"name\":\"As Diversas Realidades e a Astrologia - C.E.A.P.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\"},\"datePublished\":\"2017-12-13T14:21:36+00:00\",\"dateModified\":\"2017-12-13T14:22:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/as-diversas-realidades-e-a-astrologia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/as-diversas-realidades-e-a-astrologia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/as-diversas-realidades-e-a-astrologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As Diversas Realidades e a Astrologia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"name\":\"C.E.A.P.\",\"description\":\"Centro de Estudos de Astrologia Psicol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\",\"name\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"contentUrl\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"width\":140,\"height\":174,\"caption\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/astroceap\\\/\",\"https:\\\/\\\/x.com\\\/astrologiaceap\",\"https:\\\/\\\/www.instagram.com\\\/ceap.astrologia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDsKeXx5S7f2xoPUxNpARSQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/d0e55c0b606b43806744ff7d1d211616\",\"name\":\"geoadm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g\",\"caption\":\"geoadm\"},\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/author\\\/geoadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As Diversas Realidades e a Astrologia - C.E.A.P.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"As Diversas Realidades e a Astrologia - C.E.A.P.","og_description":"por Elizabeth Nakata \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 No Castelo de Chambord, no Vale do Loire (Fran\u00e7a), a escada principal foi projetada por Leonardo da Vinci. Uma escada nem sempre \u00e9 apenas uma escada, e essa \u00e9 especial. Ela tem o formato da h\u00e9lice","og_url":"https:\/\/astroceap.com.br\/ceap\/as-diversas-realidades-e-a-astrologia\/","og_site_name":"C.E.A.P.","article_publisher":"https:\/\/www.facebook.com\/astroceap\/","article_published_time":"2017-12-13T14:21:36+00:00","article_modified_time":"2017-12-13T14:22:54+00:00","author":"geoadm","twitter_card":"summary_large_image","twitter_creator":"@astrologiaceap","twitter_site":"@astrologiaceap","twitter_misc":{"Escrito por":"geoadm","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astroceap.com.br\/ceap\/as-diversas-realidades-e-a-astrologia\/#article","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/as-diversas-realidades-e-a-astrologia\/"},"author":{"name":"geoadm","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/d0e55c0b606b43806744ff7d1d211616"},"headline":"As Diversas Realidades e a Astrologia","datePublished":"2017-12-13T14:21:36+00:00","dateModified":"2017-12-13T14:22:54+00:00","mainEntityOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/as-diversas-realidades-e-a-astrologia\/"},"wordCount":726,"publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"articleSection":["ARTIGOS NACIONAIS"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/astroceap.com.br\/ceap\/as-diversas-realidades-e-a-astrologia\/","url":"https:\/\/astroceap.com.br\/ceap\/as-diversas-realidades-e-a-astrologia\/","name":"As Diversas Realidades e a Astrologia - C.E.A.P.","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/#website"},"datePublished":"2017-12-13T14:21:36+00:00","dateModified":"2017-12-13T14:22:54+00:00","breadcrumb":{"@id":"https:\/\/astroceap.com.br\/ceap\/as-diversas-realidades-e-a-astrologia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astroceap.com.br\/ceap\/as-diversas-realidades-e-a-astrologia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/astroceap.com.br\/ceap\/as-diversas-realidades-e-a-astrologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/astroceap.com.br\/ceap\/"},{"@type":"ListItem","position":2,"name":"As Diversas Realidades e a Astrologia"}]},{"@type":"WebSite","@id":"https:\/\/astroceap.com.br\/ceap\/#website","url":"https:\/\/astroceap.com.br\/ceap\/","name":"C.E.A.P.","description":"Centro de Estudos de Astrologia Psicol\u00f3gica","publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astroceap.com.br\/ceap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/astroceap.com.br\/ceap\/#organization","name":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica","url":"https:\/\/astroceap.com.br\/ceap\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/","url":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","contentUrl":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","width":140,"height":174,"caption":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/astroceap\/","https:\/\/x.com\/astrologiaceap","https:\/\/www.instagram.com\/ceap.astrologia\/","https:\/\/www.youtube.com\/channel\/UCDsKeXx5S7f2xoPUxNpARSQ"]},{"@type":"Person","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/d0e55c0b606b43806744ff7d1d211616","name":"geoadm","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g","caption":"geoadm"},"url":"https:\/\/astroceap.com.br\/ceap\/author\/geoadm\/"}]}},"_links":{"self":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/comments?post=721"}],"version-history":[{"count":2,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/721\/revisions"}],"predecessor-version":[{"id":723,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/721\/revisions\/723"}],"wp:attachment":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media?parent=721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/categories?post=721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/tags?post=721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}