{"id":747,"date":"2017-12-14T07:12:39","date_gmt":"2017-12-14T09:12:39","guid":{"rendered":"http:\/\/astroceap.com.br\/ceap\/?p=747"},"modified":"2017-12-14T07:12:39","modified_gmt":"2017-12-14T09:12:39","slug":"donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1","status":"publish","type":"post","link":"https:\/\/astroceap.com.br\/ceap\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\/","title":{"rendered":"DONALD TRUMP: SEUS PROBLEMAS COM AS MULHERES &#8211; An\u00e1lise do Mapa Parte 1"},"content":{"rendered":"<h4>por M\u00e1rcia Ferreira Silva<\/h4>\n<h4>AN\u00c1LISE DO MAPA DE DONALD TRUMP &#8211; Parte 1<\/h4>\n<p class=\"p2\"><img decoding=\"async\" src=\"http:\/\/www.astrologiaceap.com.br\/cms_base\/site\/cms\/ckfinder\/userfiles\/images\/DONALD TRUMP.png\" alt=\"\" \/><\/p>\n<p class=\"p2\"><strong>Animus &#8211; Princ\u00edpio masculino\u00a0<\/strong><\/p>\n<p class=\"p2\">De forma geral, segundo a psicologia anal\u00edtica de Jung, podemos dizer que o arqu\u00e9tipo Animus est\u00e1 ligado ao princ\u00edpio masculino, o qual \u00e9 representado por atividades objetivas. A forma impessoal, pragm\u00e1tica e racional para entrar em contato com as coisas, com o predom\u00ednio do Logos e uma coloca\u00e7\u00e3o menos conectada com sentimentos, criatividade e intui\u00e7\u00e3o, os quais estariam mais relacionados com o Eros e a Anima.<\/p>\n<p class=\"p2\">Para um homem, nos mostra como ele lida com a figura feminina internalizada e tamb\u00e9m com a sua pr\u00f3pria masculinidade: com as energias de agressividade, assertividade, sexualidade, vontade e coloca\u00e7\u00e3o profissional no mundo.<\/p>\n<p class=\"p2\">Em mapas astrol\u00f3gicos, podemos pensar em uma esp\u00e9cie de Animus assumindo o controle da personalidade tanto no caso de homens como no de mulheres quando encontramos uma grande \u00eanfase em signos masculinos, que s\u00e3o os signos dos elementos fogo e ar, por exemplo:<\/p>\n<p class=\"p2\">* Quando temos Sol, Lua e ASC, um Stellium ou uma preponder\u00e2ncia de planetas colocados em signos masculinos, os quais s\u00e3o: \u00c1ries, G\u00eameos, Le\u00e3o, Libra, Sagit\u00e1rio e Aqu\u00e1rio<\/p>\n<p class=\"p2\">* Quando encontramos planetas yang como Marte, J\u00fapiter, Urano e Plut\u00e3o em destaque como planetas angulares ou com aspectos e configura\u00e7\u00f5es tensas pois nesses casos a energia desses impulsos ( planetas ) sente uma prem\u00eancia e uma press\u00e3o maiores para se expressar.<\/p>\n<p class=\"p2\">Se algumas dessas condi\u00e7\u00f5es estiverem enfatizadas em um mapa, podemos inferir que se trata de uma personalidade com uma preval\u00eancia do Logos, do masculino, do pensamento, de muita objetividade, julgamento, menos intui\u00e7\u00e3o e sensibilidade, pois estas \u00faltimas pertencem ao reino da Anima. E por \u00faltimo mas n\u00e3o menos\u00a0 importante, provavelmente menos aberto a quest\u00f5es internas e ps\u00edquicas, j\u00e1 que os signos masculinos s\u00e3o mais voltados para fora e menos voltados para intimidade e nu\u00e2ncias internas.<\/p>\n<p class=\"p2\">A primeira coisa a se notar no mapa de Donald Trump \u00e9 o seu ASC em Le\u00e3o, no elemento fogo, tamb\u00e9m signo masculino. Um ASC em Le\u00e3o j\u00e1 nos fala das necessidades de obter aten\u00e7\u00e3o, de vaidade, de orgulho, de busca de reconhecimento, de ser tratado como uma pessoa muito especial e de ser amado e cortejado.<\/p>\n<p class=\"p2\">Em seguida notamos que ele tem o planeta Marte colocado a 3 graus de seu ASC, o que demonstra uma Persona ou m\u00e1scara social bastante agressiva, assertiva, de muita competitividade e a\u00e7\u00e3o.<\/p>\n<p class=\"p2\">Se o ASC est\u00e1 mais ligado com a nossa personalidade aparente e como nos colocamos no mundo, Marte no ASC tamb\u00e9m nos fala de caracter\u00edsticas masculinas ou de um Animus muito presente em sua personalidade consciente, o que nos leva a pensar numa Anima &#8211; ou princ\u00edpio feminino &#8211; mais reprimida no inconsciente na forma de Sombra. Portanto, a conex\u00e3o com o Eros, com os sentimentos, com a intui\u00e7\u00e3o e sensibilidade, ou seja, a conex\u00e3o com o amor estaria mais bloqueada e reprimida em sua personalidade. Da mesma forma a rela\u00e7\u00e3o com a figura feminina se torna algo mais distante, desconhecido e por isso mesmo podendo se tornar algo amedrontador.<\/p>\n<p class=\"p2\">Trump tem o Sol em G\u00eameos e a Lua em Sagit\u00e1rio, que s\u00e3o tamb\u00e9m signos masculinos, sobre os quais falaremos mais adiante.<\/p>\n<p class=\"p2\">Se tent\u00e1ssemos tra\u00e7ar um paralelo com os Tipos Psicol\u00f3gicos de Jung, ele se encaixaria no Tipo Intui\u00e7\u00e3o &#8211; Pensamento. Intui\u00e7\u00e3o pela inova\u00e7\u00e3o, um lan\u00e7ar-se em possibilidades futuras com uma percep\u00e7\u00e3o global e o Pensamento por uma orienta\u00e7\u00e3o mais intelectual, l\u00f3gica, o que vai de encontro com a sua predomin\u00e2ncia do Animus falado acima e o que corresponderia na astrologia \u00e0 predomin\u00e2ncia de fogo, seguido do elemento ar, ambos elementos masculinos. Por outro lado, as fun\u00e7\u00f5es Sensa\u00e7\u00e3o, que nos fala de percep\u00e7\u00f5es mais concretas e pr\u00e1ticas e a fun\u00e7\u00e3o Sentimento ficam relegadas \u00e0 Sombra e com mais dificuldade de acesso. O elemento \u00e1gua est\u00e1 presente em menor grau em seu mapa e o que \u00e9 interessante de observarmos \u00e9 que ele tem zero ponto no elemento terra. Tudo isso j\u00e1 pode nos fazer supor que sua fortuna tenha se dado muito mais por arroubos, grandes vis\u00f5es e sacadas grandiosas do que por um trabalho mais de \u201cformiguinha\u201d e \u201cp\u00e9-no-ch\u00e3o\u201d e nos leva a pensar at\u00e9 em falta de alicerces de base ou negligencias em quest\u00f5es de ordem pr\u00e1tica e concreta.<\/p>\n<p class=\"p2\">\n<p class=\"p2\"><strong>Anima &#8211; Princ\u00edpio feminino<\/strong><\/p>\n<p class=\"p2\">Em termos da Anima, nos chama muito a aten\u00e7\u00e3o o fato de Trump ter nascido sob uma lua cheia e principalmente num eclipse lunar, com a Lua em conjun\u00e7\u00e3o ao Nodo Sul. Num eclipse lunar total, a Lua \u00e9 coberta pela sombra da Terra e basicamente desaparece.<\/p>\n<p class=\"p2\">Se pensarmos no simbolismo da Lua, o princ\u00edpio e toda a liga\u00e7\u00e3o com a figura feminina ficam ent\u00e3o obscurecidos, prevalecendo o Sol e o masculino. As quest\u00f5es emocionais e toda a parte sentimental reprimidas no inconsciente e com dif\u00edcil acesso \u00e0 consci\u00eancia, funcionando mais ou menos como uma \u201cpanela de press\u00e3o\u201d, pronta a explodir. Muitos acontecimentos terrestres s\u00e3o precipitados pela lua cheia, como as mar\u00e9s, altera\u00e7\u00f5es de humores nas pessoas e tantos outros. Um eclipse lunar traz tudo isso em potencial, por\u00e9m de forma mais dif\u00edcil de ser acessada.<\/p>\n<p class=\"p2\">Nascer sob o impacto de um eclipse lunar, que n\u00e3o deixa de ser uma lua cheia, significa ter nascido sob a \u00e9gide de uma polariza\u00e7\u00e3o entre o masculino e o feminino onde os dois princ\u00edpios se antagonizam e com dif\u00edcil integra\u00e7\u00e3o, a n\u00e3o ser que haja grande e intenso trabalho ps\u00edquico.<\/p>\n<p class=\"p2\">Al\u00e9m disso, o aspecto astrol\u00f3gico de oposi\u00e7\u00e3o entre Sol e Lua, existente em uma lua cheia, por si s\u00f3 j\u00e1 nos fala sobre a necessidade inconsciente de utilizar o mecanismo de defesa que se chama em psican\u00e1lise de Identifica\u00e7\u00e3o Projetiva: os conte\u00fados n\u00e3o-aceitos e negados s\u00e3o projetados no outro e a pessoa fica esvaziada desses conte\u00fados sombrios. O outro recebe essa proje\u00e7\u00e3o maci\u00e7a e com isso a pessoa meio que \u201ccontrola\u201d a mente da pessoa receptora da proje\u00e7\u00e3o.<\/p>\n<p class=\"p2\">O mundo todo acompanhou e assistiu os ataques que Trump tem lan\u00e7ado contra Hillary Clinton nos debates para a presid\u00eancia e os ataques desrespeitosos contra as mulheres e tantos outros em geral, como que se colocando a partir de uma preval\u00eancia e arrog\u00e2ncia masculina com o intuito de desvalorizar e subestimar o outro e o feminino. Chegou a acusar Hillary em pleno palco no debate de \u201cmulher antip\u00e1tica, s\u00f3rdida\u201d ou em outro momento: \u201cvoc\u00ea tem muito \u00f3dio em seu cora\u00e7\u00e3o\u201d. Vemos a\u00ed com muita clareza um mecanismo de Identifica\u00e7\u00e3o Projetiva maci\u00e7a pois ele se esvazia desses \u201cmaus\u201d conte\u00fados, provocando quase que um nocaute em seu opositor, no caso, Hillary.<\/p>\n<p class=\"p2\">Ainda em termos dessa polaridade, podemos notar que o Sol de Trump se encontra na casa X, uma casa de grande proemin\u00eancia profissional e ainda em conjun\u00e7\u00e3o com o seu Nodo Norte, o que fortalece o planeta de ambas as maneiras. Isso lhe d\u00e1 uma grande atua\u00e7\u00e3o e visibilidade no mundo e uma t\u00f4nica profissional extremamente forte, prevalecendo assim mais uma vez o masculino e a assertividade. J\u00e1 a Lua em conjun\u00e7\u00e3o ao Nodo Sul, fica com sua energia enfraquecida e segundo a astrologia k\u00e1rmica, isto significaria que Trump traz nessa vida um problema k\u00e1rmico de vidas passadas em rela\u00e7\u00e3o \u00e0 figura feminina, de forma a repetir padr\u00f5es inconscientes e problem\u00e1ticos de maneira compulsiva.<\/p>\n<p class=\"p2\">Outras faces do arqu\u00e9tipo da Anima s\u00e3o a Lilith ou Lua Negra e o planeta V\u00eanus. Tanto a Lua como a Lilith se encontram em sua Casa IV, o setor das nossas origens, background, passado e p\u00e1tria. A Casa IV \u00e9 uma casa ps\u00edquica e inconsciente, onde os conte\u00fados n\u00e3o s\u00e3o facilmente acessados na consci\u00eancia e ficam pulsando, n\u00e3o encontrando vaz\u00e3o e integra\u00e7\u00e3o na personalidade. Trump, buscando essa proemin\u00eancia e a presid\u00eancia em sua p\u00e1tria de origem, que s\u00e3o quest\u00f5es de Lua e Casa IV, estaria indo na dire\u00e7\u00e3o de repetir esse passado k\u00e1rmico pois \u00e9 onde se encontra o seu Nodo Sul, que na verdade o remete a problem\u00e1ticas e a confus\u00f5es e n\u00e3o ao direcionamento que ele deveria seguir, o de Casa X, sua pr\u00f3pria atua\u00e7\u00e3o profissional. O fato de estar preso ao Nodo Sul poder\u00e1 trazer consequ\u00eancias s\u00e9rias e de muitos problemas a ele pessoalmente, como os que ele j\u00e1 est\u00e1 se envolvendo, como veremos na Parte 2.<\/p>\n<p class=\"p2\">V\u00eanus complementa a imago feminina na psique. Vemos que Trump tem uma V\u00eanus em conjun\u00e7\u00e3o a Saturno, onde essa id\u00e9ia novamente nos remete a uma repress\u00e3o e uma anula\u00e7\u00e3o do feminino, do Eros, e o que tamb\u00e9m mais uma vez corrobora toda a sua dificuldade com as mulheres e seus impulsos repressores para com elas.<\/p>\n<p class=\"p2\">\n<p class=\"p2\"><strong>Texto escrito por M\u00e1rcia Ferreira Silva, ISAR C.A.P.<\/strong><\/p>\n<p class=\"p1\"><strong>www.astroceap.com.br<\/strong><\/p>\n<p class=\"p1\"><strong>marciaf@astrologiaceap.com.br<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>por M\u00e1rcia Ferreira Silva AN\u00c1LISE DO MAPA DE DONALD TRUMP &#8211; Parte 1 Animus &#8211; Princ\u00edpio masculino\u00a0 De forma geral, segundo a psicologia anal\u00edtica de Jung, podemos dizer que o arqu\u00e9tipo Animus est\u00e1 ligado ao princ\u00edpio masculino, o qual \u00e9<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-747","post","type-post","status-publish","format-standard","hentry","category-artigos-nacionais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DONALD TRUMP: SEUS PROBLEMAS COM AS MULHERES - An\u00e1lise do Mapa Parte 1 - C.E.A.P.<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DONALD TRUMP: SEUS PROBLEMAS COM AS MULHERES - An\u00e1lise do Mapa Parte 1 - C.E.A.P.\" \/>\n<meta property=\"og:description\" content=\"por M\u00e1rcia Ferreira Silva AN\u00c1LISE DO MAPA DE DONALD TRUMP &#8211; Parte 1 Animus &#8211; Princ\u00edpio masculino\u00a0 De forma geral, segundo a psicologia anal\u00edtica de Jung, podemos dizer que o arqu\u00e9tipo Animus est\u00e1 ligado ao princ\u00edpio masculino, o qual \u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astroceap.com.br\/ceap\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\/\" \/>\n<meta property=\"og:site_name\" content=\"C.E.A.P.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/astroceap\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-14T09:12:39+00:00\" \/>\n<meta name=\"author\" content=\"geoadm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:site\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"geoadm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\\\/\"},\"author\":{\"name\":\"geoadm\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/d0e55c0b606b43806744ff7d1d211616\"},\"headline\":\"DONALD TRUMP: SEUS PROBLEMAS COM AS MULHERES &#8211; An\u00e1lise do Mapa Parte 1\",\"datePublished\":\"2017-12-14T09:12:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\\\/\"},\"wordCount\":1587,\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"articleSection\":[\"ARTIGOS NACIONAIS\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\\\/\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\\\/\",\"name\":\"DONALD TRUMP: SEUS PROBLEMAS COM AS MULHERES - An\u00e1lise do Mapa Parte 1 - C.E.A.P.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\"},\"datePublished\":\"2017-12-14T09:12:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DONALD TRUMP: SEUS PROBLEMAS COM AS MULHERES &#8211; An\u00e1lise do Mapa Parte 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"name\":\"C.E.A.P.\",\"description\":\"Centro de Estudos de Astrologia Psicol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\",\"name\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"contentUrl\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"width\":140,\"height\":174,\"caption\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/astroceap\\\/\",\"https:\\\/\\\/x.com\\\/astrologiaceap\",\"https:\\\/\\\/www.instagram.com\\\/ceap.astrologia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDsKeXx5S7f2xoPUxNpARSQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/d0e55c0b606b43806744ff7d1d211616\",\"name\":\"geoadm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g\",\"caption\":\"geoadm\"},\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/author\\\/geoadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DONALD TRUMP: SEUS PROBLEMAS COM AS MULHERES - An\u00e1lise do Mapa Parte 1 - C.E.A.P.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"DONALD TRUMP: SEUS PROBLEMAS COM AS MULHERES - An\u00e1lise do Mapa Parte 1 - C.E.A.P.","og_description":"por M\u00e1rcia Ferreira Silva AN\u00c1LISE DO MAPA DE DONALD TRUMP &#8211; Parte 1 Animus &#8211; Princ\u00edpio masculino\u00a0 De forma geral, segundo a psicologia anal\u00edtica de Jung, podemos dizer que o arqu\u00e9tipo Animus est\u00e1 ligado ao princ\u00edpio masculino, o qual \u00e9","og_url":"https:\/\/astroceap.com.br\/ceap\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\/","og_site_name":"C.E.A.P.","article_publisher":"https:\/\/www.facebook.com\/astroceap\/","article_published_time":"2017-12-14T09:12:39+00:00","author":"geoadm","twitter_card":"summary_large_image","twitter_creator":"@astrologiaceap","twitter_site":"@astrologiaceap","twitter_misc":{"Escrito por":"geoadm","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astroceap.com.br\/ceap\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\/#article","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\/"},"author":{"name":"geoadm","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/d0e55c0b606b43806744ff7d1d211616"},"headline":"DONALD TRUMP: SEUS PROBLEMAS COM AS MULHERES &#8211; An\u00e1lise do Mapa Parte 1","datePublished":"2017-12-14T09:12:39+00:00","mainEntityOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\/"},"wordCount":1587,"publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"articleSection":["ARTIGOS NACIONAIS"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/astroceap.com.br\/ceap\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\/","url":"https:\/\/astroceap.com.br\/ceap\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\/","name":"DONALD TRUMP: SEUS PROBLEMAS COM AS MULHERES - An\u00e1lise do Mapa Parte 1 - C.E.A.P.","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/#website"},"datePublished":"2017-12-14T09:12:39+00:00","breadcrumb":{"@id":"https:\/\/astroceap.com.br\/ceap\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astroceap.com.br\/ceap\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/astroceap.com.br\/ceap\/donald-trump-seus-problemas-com-as-mulheres-analise-do-mapa-parte-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/astroceap.com.br\/ceap\/"},{"@type":"ListItem","position":2,"name":"DONALD TRUMP: SEUS PROBLEMAS COM AS MULHERES &#8211; An\u00e1lise do Mapa Parte 1"}]},{"@type":"WebSite","@id":"https:\/\/astroceap.com.br\/ceap\/#website","url":"https:\/\/astroceap.com.br\/ceap\/","name":"C.E.A.P.","description":"Centro de Estudos de Astrologia Psicol\u00f3gica","publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astroceap.com.br\/ceap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/astroceap.com.br\/ceap\/#organization","name":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica","url":"https:\/\/astroceap.com.br\/ceap\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/","url":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","contentUrl":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","width":140,"height":174,"caption":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/astroceap\/","https:\/\/x.com\/astrologiaceap","https:\/\/www.instagram.com\/ceap.astrologia\/","https:\/\/www.youtube.com\/channel\/UCDsKeXx5S7f2xoPUxNpARSQ"]},{"@type":"Person","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/d0e55c0b606b43806744ff7d1d211616","name":"geoadm","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8934feaa4cd81148cd2d740b488c2647b17edd7f19fdaf448a0327dee72a48c0?s=96&d=blank&r=g","caption":"geoadm"},"url":"https:\/\/astroceap.com.br\/ceap\/author\/geoadm\/"}]}},"_links":{"self":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/comments?post=747"}],"version-history":[{"count":1,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/747\/revisions"}],"predecessor-version":[{"id":748,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/747\/revisions\/748"}],"wp:attachment":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media?parent=747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/categories?post=747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/tags?post=747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}