{"id":8586,"date":"2021-01-15T18:26:31","date_gmt":"2021-01-15T21:26:31","guid":{"rendered":"http:\/\/astroceap.com.br\/ceap\/?p=8586"},"modified":"2021-01-15T18:27:48","modified_gmt":"2021-01-15T21:27:48","slug":"2021-e-as-quadraturas-entre-urano-e-saturno","status":"publish","type":"post","link":"https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/","title":{"rendered":"2021 E AS QUADRATURAS ENTRE URANO E SATURNO"},"content":{"rendered":"<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div><img decoding=\"async\" class=\"aligncenter size-full wp-image-8600 lazyload\" data-src=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/small-URANO.jpg\" alt=\"\" width=\"800\" height=\"800\" data-srcset=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/small-URANO.jpg 800w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/small-URANO-300x300.jpg 300w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/small-URANO-150x150.jpg 150w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/small-URANO-768x768.jpg 768w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/small-URANO-230x230.jpg 230w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/small-URANO-330x330.jpg 330w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/800;\" \/><\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>\n<p><span style=\"color: #000000;\">Preste aten\u00e7\u00e3o e procure entender bem o planeta Urano: como ele est\u00e1 em em seu mapa, que casa ele rege e como ele tem se expressado em sua vida, pois voc\u00ea vai ouvir falar muito sobre este planeta ao longo de 2021!<\/span><\/p>\n<p><span style=\"color: #000000;\">Neste momento Urano est\u00e1 retomando seu movimento direto, assim como todos os outros planetas j\u00e1 se encontram diretos agora, o que \u00e9 uma boa not\u00edcia. Dessa forma, sua express\u00e3o passa a ficar mais livre e mais aberta para poder deixar fluir suas qualidades de abertura para o novo, modernidade, quebra de paradigmas, avan\u00e7os cient\u00edficos e tecnol\u00f3gicos, mas tamb\u00e9m rompimentos s\u00fabitos, confrontos e rebeldias.<\/span><\/p>\n<p><span style=\"color: #000000;\">Temos falado que o pior j\u00e1 passou e \u00e9 verdade, pois as configura\u00e7\u00f5es celestes que se apresentaram em 2019\/2020 repetiam momentos hist\u00f3ricos onde houveram cat\u00e1strofes com exterm\u00ednio da humanidade, e isto infelizmente se repetiu, mas tais aspectos j\u00e1 se desfizeram e tudo isso portanto tende a diminuir.<\/span><\/p>\n<p><span style=\"color: #000000;\">Come\u00e7amos este ano com a id\u00e9ia do novo, j\u00e1 com esse ingresso hist\u00f3rico da conjun\u00e7\u00e3o entre J\u00fapiter e Saturno em Aqu\u00e1rio, pontuando um marco forte nesta longa transi\u00e7\u00e3o para a Era de Aqu\u00e1rio em que a humanidade se encontra, o que ir\u00e1 nos trazer nessa d\u00e9cada de 20 principalmente, muitos avan\u00e7os cient\u00edficos e tecnol\u00f3gicos, uma nova mentalidade e uma grande mudan\u00e7a de paradigmas, onde o conhecimento ocupar\u00e1 um lugar central em detrimento de uma pol\u00edtica capitalista e territorialista, a qual vem vindo desde a Revolu\u00e7\u00e3o Industrial. Temos falado muito ultimamente sobre este ingresso que ocorreu no \u00faltimo dezembro ( veja v\u00eddeos no Youtube ), o qual j\u00e1 come\u00e7ou com o lan\u00e7amento de uma tecnologia inovadora das vacinas.<\/span><\/p>\n<p><span style=\"color: #000000;\">POR\u00c9M, como popularmente se diz, \u201cN\u00e3o se faz um omelete sem se quebrar os ovos \u201c, e em 2021 teremos como marco importante as quadraturas entre Urano ( em Touro ) e Saturno ( em Aqu\u00e1rio ), que ter\u00e3o 03 picos de tens\u00e3o, dando-se em graus exatos ao longo do ano:<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">nos graus 06 e 07 em Fevereiro\/21 ( signos de Touro e Aqu\u00e1rio )<\/span><\/li>\n<li><span style=\"color: #000000;\">no grau 13 em Junho\/21 ( signos de Touro e Aqu\u00e1rio )<\/span><\/li>\n<li><span style=\"color: #000000;\">no grau 11 em Dezembro\/21 ( signos de Touro e Aqu\u00e1rio )<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000000;\">Estas quadraturas mexem com toda a modernidade proposta com o ingresso mencionado acima no signo de Aqu\u00e1rio, pois ambos os planetas s\u00e3o regentes deste signo e tanto Touro como Aqu\u00e1rio resistem \u00e0s mudan\u00e7as, cada um a seu modo.<\/span><\/p>\n<p><span style=\"color: #000000;\">Onde esta tens\u00e3o se d\u00e1 em seu mapa?<\/span><\/p>\n<p><span style=\"color: #000000;\">O significado simb\u00f3lico deste aspecto \u00e9 este embate entre a tradi\u00e7\u00e3o e a necessidade de reformas sociais, o conflito entre o velho e o novo, uma nova ordem vindo para derrubar a antiga e a resist\u00eancia a isso, conflitos com autoridades estabelecidas e os cortes abruptos no modo de enfrentamento.<\/span><\/p>\n<p><span style=\"color: #000000;\">Como defesas contra essas tend\u00eancias coletivas, de um lado h\u00e1 o enrijecimento e os temores de perder-se nos novos valores e de se perder tudo o que \u00e9 conhecido e que foi duramente conquistado, com antecipa\u00e7\u00f5es temerosas e rejei\u00e7\u00f5es a qualquer nova onda.<\/span><\/p>\n<p><span style=\"color: #000000;\">De outro lado, \u00e9 como se houvesse uma prem\u00eancia para que tudo se modificasse abruptamente: \u201cEst\u00e1 tudo p\u00e9ssimo desse jeito antigo, quero fazer tudo completamente novo e diferente\u201d ou \u201cAbaixo as estruturas!\u201d, uma rejei\u00e7\u00e3o ao antigo e \u00e0s autoridades que o representam, com o desejo de se romper com tudo, assim, de repente. A figura abaixo ilustra bem este momento.<\/span><\/p>\n<p><span style=\"color: #000000;\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-8601 lazyload\" data-src=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/PeAreia.jpg\" alt=\"\" width=\"225\" height=\"225\" data-srcset=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/PeAreia.jpg 225w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/PeAreia-150x150.jpg 150w\" data-sizes=\"(max-width: 225px) 100vw, 225px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 225px; --smush-placeholder-aspect-ratio: 225\/225;\" \/><\/span><\/p>\n<p><span style=\"color: #000000;\">Por tr\u00e1s de tudo isso, processos depressivos e temores, faltas, car\u00eancias, sensa\u00e7\u00e3o de impot\u00eancia e de n\u00e3o se conseguir ser compreendido. Embates, confrontos, lutas sociais.<\/span><\/p>\n<p><span style=\"color: #000000;\">Este \u00e9 o pano de fundo deste ano e o que iremos assistir repetidamente daqui para frente. As mudan\u00e7as sempre acontecem n\u00e3o sem o suor das lutos e sofrimentos e os sentimentos de perda. Para poder vir algo novo no lugar, o velho tem que abrir espa\u00e7o, deve acontecer uma destrui\u00e7\u00e3o e uma re-constru\u00e7\u00e3o, t\u00e3o bem representadas pelo aspecto atual entre estes planetas, para que se possa finalmente construir uma ponte entre o velho e o novo, liberando as estruturas precedentes.<\/span><\/p>\n<p><span style=\"color: #000000;\">Como exemplo de outras \u00e9pocas de mudan\u00e7as de paradigmas, temos os exemplares vivos dos nascidos nos anos 40, os que passaram sua mocidade na d\u00e9cada de 60 com o movimento hippie, e que parece que tiveram como miss\u00e3o essa quebra de paradigmas, a qual estava claramente apontada em seus mapas natais: Caetano Veloso, Gilberto Gil, Jimmy Hendrix, Bob Dylan, Paul McCartney, Janis Joplin e tantos outros.<\/span><\/p>\n<p><span style=\"color: #000000;\">Todos estes nasceram sob esta energia, a do confronto entre estes planetas Saturno e Urano, na \u00e9poca uma conjun\u00e7\u00e3o, mas que traz uma conota\u00e7\u00e3o muito semelhante. Bem, est\u00e1 a\u00ed a prova de toda a abertura de mente e de valores que eles nos trouxeram, por\u00e9m n\u00e3o sem passar pelos embates e sofrimentos inerentes \u00e0 quebra de paradigmas da \u00e9poca.<\/span><\/p>\n<p><span style=\"color: #000000;\">Nova turma da Forma\u00e7\u00e3o come\u00e7ando em janeiro. Saiba mais em: <a style=\"color: #000000;\" href=\"https:\/\/mailchi.mp\/618440eef7eb\/1mosyiyw6p\">https:\/\/mailchi.mp\/618440eef7eb\/1mosyiyw6p<\/a><\/span><\/p>\n<p><span style=\"color: #000000;\">Texto de M\u00e1rcia Ferreira<\/span><br \/>\n<span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/astroceap.com.br\/ceap\/\">www.astrologiaceap.com.br<\/a><\/span><br \/>\n<span style=\"color: #000000;\">Whats: (19) 3258-8342<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Preste aten\u00e7\u00e3o e procure entender bem o planeta Urano: como ele est\u00e1 em em seu mapa, que casa ele rege e como ele tem se expressado em sua vida, pois voc\u00ea vai ouvir falar muito<\/p>\n","protected":false},"author":2,"featured_media":8600,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-8586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2021 E AS QUADRATURAS ENTRE URANO E SATURNO - C.E.A.P.<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2021 E AS QUADRATURAS ENTRE URANO E SATURNO - C.E.A.P.\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Preste aten\u00e7\u00e3o e procure entender bem o planeta Urano: como ele est\u00e1 em em seu mapa, que casa ele rege e como ele tem se expressado em sua vida, pois voc\u00ea vai ouvir falar muito\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/\" \/>\n<meta property=\"og:site_name\" content=\"C.E.A.P.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/astroceap\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-15T21:26:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-15T21:27:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/small-URANO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00e1rcia Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:site\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00e1rcia Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2021-e-as-quadraturas-entre-urano-e-saturno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2021-e-as-quadraturas-entre-urano-e-saturno\\\/\"},\"author\":{\"name\":\"M\u00e1rcia Ferreira\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/71c3b7859d3eb1da9042ec5ff95f0f19\"},\"headline\":\"2021 E AS QUADRATURAS ENTRE URANO E SATURNO\",\"datePublished\":\"2021-01-15T21:26:31+00:00\",\"dateModified\":\"2021-01-15T21:27:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2021-e-as-quadraturas-entre-urano-e-saturno\\\/\"},\"wordCount\":869,\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2021-e-as-quadraturas-entre-urano-e-saturno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/small-URANO.jpg\",\"articleSection\":[\"BLOG\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2021-e-as-quadraturas-entre-urano-e-saturno\\\/\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2021-e-as-quadraturas-entre-urano-e-saturno\\\/\",\"name\":\"2021 E AS QUADRATURAS ENTRE URANO E SATURNO - C.E.A.P.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2021-e-as-quadraturas-entre-urano-e-saturno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2021-e-as-quadraturas-entre-urano-e-saturno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/small-URANO.jpg\",\"datePublished\":\"2021-01-15T21:26:31+00:00\",\"dateModified\":\"2021-01-15T21:27:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2021-e-as-quadraturas-entre-urano-e-saturno\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2021-e-as-quadraturas-entre-urano-e-saturno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2021-e-as-quadraturas-entre-urano-e-saturno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/small-URANO.jpg\",\"contentUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/small-URANO.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/2021-e-as-quadraturas-entre-urano-e-saturno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2021 E AS QUADRATURAS ENTRE URANO E SATURNO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"name\":\"C.E.A.P.\",\"description\":\"Centro de Estudos de Astrologia Psicol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\",\"name\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"contentUrl\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"width\":140,\"height\":174,\"caption\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/astroceap\\\/\",\"https:\\\/\\\/x.com\\\/astrologiaceap\",\"https:\\\/\\\/www.instagram.com\\\/ceap.astrologia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDsKeXx5S7f2xoPUxNpARSQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/71c3b7859d3eb1da9042ec5ff95f0f19\",\"name\":\"M\u00e1rcia Ferreira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"caption\":\"M\u00e1rcia Ferreira\"},\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/author\\\/marcia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2021 E AS QUADRATURAS ENTRE URANO E SATURNO - C.E.A.P.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"2021 E AS QUADRATURAS ENTRE URANO E SATURNO - C.E.A.P.","og_description":"&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Preste aten\u00e7\u00e3o e procure entender bem o planeta Urano: como ele est\u00e1 em em seu mapa, que casa ele rege e como ele tem se expressado em sua vida, pois voc\u00ea vai ouvir falar muito","og_url":"https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/","og_site_name":"C.E.A.P.","article_publisher":"https:\/\/www.facebook.com\/astroceap\/","article_published_time":"2021-01-15T21:26:31+00:00","article_modified_time":"2021-01-15T21:27:48+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/small-URANO.jpg","type":"image\/jpeg"}],"author":"M\u00e1rcia Ferreira","twitter_card":"summary_large_image","twitter_creator":"@astrologiaceap","twitter_site":"@astrologiaceap","twitter_misc":{"Escrito por":"M\u00e1rcia Ferreira","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/#article","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/"},"author":{"name":"M\u00e1rcia Ferreira","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/71c3b7859d3eb1da9042ec5ff95f0f19"},"headline":"2021 E AS QUADRATURAS ENTRE URANO E SATURNO","datePublished":"2021-01-15T21:26:31+00:00","dateModified":"2021-01-15T21:27:48+00:00","mainEntityOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/"},"wordCount":869,"publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/small-URANO.jpg","articleSection":["BLOG"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/","url":"https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/","name":"2021 E AS QUADRATURAS ENTRE URANO E SATURNO - C.E.A.P.","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/#primaryimage"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/small-URANO.jpg","datePublished":"2021-01-15T21:26:31+00:00","dateModified":"2021-01-15T21:27:48+00:00","breadcrumb":{"@id":"https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/#primaryimage","url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/small-URANO.jpg","contentUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2021\/01\/small-URANO.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/astroceap.com.br\/ceap\/2021-e-as-quadraturas-entre-urano-e-saturno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/astroceap.com.br\/ceap\/"},{"@type":"ListItem","position":2,"name":"2021 E AS QUADRATURAS ENTRE URANO E SATURNO"}]},{"@type":"WebSite","@id":"https:\/\/astroceap.com.br\/ceap\/#website","url":"https:\/\/astroceap.com.br\/ceap\/","name":"C.E.A.P.","description":"Centro de Estudos de Astrologia Psicol\u00f3gica","publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astroceap.com.br\/ceap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/astroceap.com.br\/ceap\/#organization","name":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica","url":"https:\/\/astroceap.com.br\/ceap\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/","url":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","contentUrl":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","width":140,"height":174,"caption":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/astroceap\/","https:\/\/x.com\/astrologiaceap","https:\/\/www.instagram.com\/ceap.astrologia\/","https:\/\/www.youtube.com\/channel\/UCDsKeXx5S7f2xoPUxNpARSQ"]},{"@type":"Person","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/71c3b7859d3eb1da9042ec5ff95f0f19","name":"M\u00e1rcia Ferreira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","caption":"M\u00e1rcia Ferreira"},"url":"https:\/\/astroceap.com.br\/ceap\/author\/marcia\/"}]}},"_links":{"self":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/8586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/comments?post=8586"}],"version-history":[{"count":7,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/8586\/revisions"}],"predecessor-version":[{"id":8603,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/8586\/revisions\/8603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media\/8600"}],"wp:attachment":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media?parent=8586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/categories?post=8586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/tags?post=8586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}