{"id":8850,"date":"2021-04-29T17:10:53","date_gmt":"2021-04-29T20:10:53","guid":{"rendered":"http:\/\/astroceap.com.br\/ceap\/?p=8850"},"modified":"2021-04-29T17:16:27","modified_gmt":"2021-04-29T20:16:27","slug":"desafios-comuns-em-consulta","status":"publish","type":"post","link":"https:\/\/astroceap.com.br\/ceap\/desafios-comuns-em-consulta\/","title":{"rendered":"DESAFIOS COMUNS EM CONSULTA"},"content":{"rendered":"<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Desafios comuns nas Consultas Astrol\u00f3gicas <\/strong><\/span><\/h4>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>por Maurice Fernandez<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>A Astrologia tem capturado de forma irrevers\u00edvel os cora\u00e7\u00f5es e mentes de muitos de n\u00f3s, muitas vezes de maneiras inesperadas.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><em>Foi um livro sobre signo solar, uma leitura transformadora, ou na verdade a tentativa de desmentir a astrologia que nos colocou em nosso caminho como estudantes e praticantes?<\/em> No meu caso, eu me encontrei quando a Astrologia me encontrou. Minha confus\u00e3o, aliena\u00e7\u00e3o e vazio persistente se dissipou quando a astrologia entrou em minha vida; a vida fez sentido, talvez pela primeira vez. Suspeito que muitos outros experimentaram um senso semelhante de empoderamento por meio deste estudo.<\/span><\/p>\n<p><span style=\"color: #000000;\">A astrologia fornece uma perspectiva inigual\u00e1vel de vida, e ainda assim pode ser desafiador traduzir este vasto campo de conhecimento com muitas camadas em informa\u00e7\u00f5es acess\u00edveis. A verdade pode ser poderosa, at\u00e9 mesmo avassaladora, e sua revela\u00e7\u00e3o exige que seja feita com cuidado.<\/span><\/p>\n<p><span style=\"color: #000000;\">A experi\u00eancia e a humildade s\u00e3o essenciais para a pr\u00e1tica adequada, com a inten\u00e7\u00e3o consciente de n\u00e3o fazer nenhum mal.<\/span><\/p>\n<p><span style=\"color: #000000;\">Os astr\u00f3logos podem ter estudado para saber sobre planetas ou t\u00e9cnicas preditivas, mas <strong>poucos programas educacionais realizam treinamento em t\u00e9cnicas de atendimento e \u00e9tica em astrologia<\/strong>.<\/span><\/p>\n<p><span style=\"color: #000000;\">Considere essa realidade onde os astr\u00f3logos podem ter acesso a algumas das preocupa\u00e7\u00f5es mais \u00edntimas da vida de uma pessoa, ainda que sem ter a verdadeira experi\u00eancia em t\u00e9cnicas de atendimento, uma comunica\u00e7\u00e3o consciente e\/ou consci\u00eancia cultural. O risco de erros \u00e9 consider\u00e1vel!<\/span><\/p>\n<p><span style=\"color: #000000;\">Por meio do meu envolvimento com a OPA encontrei <strong>dezenas de relatos de pessoas que se sentiram prejudicadas durante as leituras<\/strong> porque o astr\u00f3logo n\u00e3o transmitiu as informa\u00e7\u00f5es de forma h\u00e1bil. Isto pode acontecer com os melhores de n\u00f3s; todos n\u00f3s temos nossos pontos cegos, portanto a autocritica \u00e9 importante. Com a crescente exposi\u00e7\u00e3o da astrologia nos principais meios de comunica\u00e7\u00e3o e o meio crescendo exponencialmente, quanto tempo levar\u00e1 para que uma experi\u00eancia de leitura negativa passe por algum processo jur\u00eddico? Pode ser uma boa hora de se implementar um <strong>treinamento em t\u00e9cnicas de atendimento como pr\u00e9-requisito para a pr\u00e1tica da astrologia<\/strong>.<\/span><\/p>\n<p><span style=\"color: #000000;\">Pode ser que nem sempre seja a falta de habilidade do astr\u00f3logo que leve a uma esp\u00e9cie de crise. Os clientes podem trazer suas pr\u00f3prias inseguran\u00e7as e mecanismos de defesa para a sala de consulta, e os profissionais devem lidar com os desafios potenciais da melhor forma poss\u00edvel. Queremos oferecer ajuda e servi\u00e7o da maneira mais eficaz, e isto requer navegar nas sensibilidades da nossa pr\u00f3pria condi\u00e7\u00e3o humana.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>Aqui est\u00e3o algumas quest\u00f5es importantes em uma consulta que merecem destaque<\/strong>:<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff6600;\"><strong>COMUNICA\u00c7\u00c3O EQUILIBRADA<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #800000;\"><strong>Utilizando<\/strong><strong> termos <\/strong><strong>astrol\u00f3gicos<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>Uma das muletas usadas mais frequentemente por astr\u00f3logos \u00e9 falar com jarg\u00e3o astrol\u00f3gico<\/strong>.<\/span><\/p>\n<p><span style=\"color: #000000;\">Para um astr\u00f3logo, dizer <em>&#8220;voc\u00ea vai ter uma quadratura Marte\/Saturno que vem por a\u00ed&#8221;<\/em>, significa muito; tr\u00eas palavras que envolvem uma gama de experi\u00eancias. No entanto, para um cliente, mesmo com algum conhecimento de astrologia, isso pode permanecer abstrato e dif\u00edcil de integrar. \u00c9 essencial encontrar o vocabul\u00e1rio certo para destrinchar este conceito em uma linguagem acess\u00edvel &#8211; por exemplo: \u201c<em>Este pode ser um momento em que voc\u00ea precise revisitar suas motiva\u00e7\u00f5es e modos de a\u00e7\u00e3o. Qualquer que seja o objetivo que estabele\u00e7a para voc\u00ea mesmo, seja paciente e consistente, e os resultados se mostrar\u00e3o a longo prazo. Insistir demais poder\u00e1 causar rupturas, bloqueios, ou mesmo les\u00f5es f\u00edsicas&#8221;<\/em>.<\/span><\/p>\n<p><span style=\"color: #000000;\">Diversos clientes relatam que obtiveram muito pouco ou nada de uma leitura, ou simplesmente esqueceram o que foi realmente dito, porque as informa\u00e7\u00f5es passaram batido.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>Resultado<\/strong>: Fa\u00e7a uma distin\u00e7\u00e3o entre uma consulta de astrologia e uma<\/span><\/p>\n<p><span style=\"color: #000000;\">aula de astrologia. Em uma consulta, fale com o cliente sobre a vida dele, n\u00e3o sobre os aspectos do mapa dele. Algumas refer\u00eancias astrol\u00f3gicas podem ser \u00fateis em pequenas doses.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #800000;\"><strong>Analisando o mapa planeta por planeta<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">Uma habilidade importante na interpreta\u00e7\u00e3o de mapas \u00e9 a <strong>arte da s\u00edntese<\/strong>, reunindo todos os componentes do mapa de forma coesa, da mesma forma que misturamos todos os ingredientes para fazer um bolo; a fus\u00e3o de todos esses ingredientes deve fazer uma sobremesa saborosa. A falta de s\u00edntese adequada dos componentes do mapa pode <strong>se deparar com componentes fragmentados e contradit\u00f3rios<\/strong>; passar por cada planeta, um de cada vez, pode confundir o cliente.<\/span><\/p>\n<p><span style=\"color: #000000;\">Por exemplo, pode-se come\u00e7ar com um <em>Sol em Sagit\u00e1rio<\/em> e o descrever como <\/span><span style=\"color: #000000;\">aventureiro e amante da liberdade e depois prosseguir para a <em>Lua em C\u00e2ncer<\/em>, e descrever como essa Lua representa um anseio por seguran\u00e7a e prefer\u00eancia pela rotina familiar. Em outras palavras, duas afirma\u00e7\u00f5es completamente contradit\u00f3rias se sucedem. A maioria dos mapas tem afirma\u00e7\u00f5es contradit\u00f3rias; \u00e9 a norma, e ainda assim, a maioria de n\u00f3s n\u00e3o tem personalidades divididas. Nesse caso, encontrando a maneira de sintetizar o Sol em Sagit\u00e1rio com uma Lua em C\u00e2ncer come\u00e7a com a busca de seus pontos em comum, dizendo, por exemplo: <em>Voc\u00ea \u00e9 muito leal a voc\u00ea mesmo e sua autenticidade e n\u00e3o quer se comprometer com as necessidades pessoais &#8211; as coisas t\u00eam que acontecer a seu tempo. <\/em>Ou<em> Quando voc\u00ea vai para uma aventura, tem que ser nos seus termos, e voc\u00ea precisa ter um plano B.<\/em> Estas declara\u00e7\u00f5es fundem as qualidades contradit\u00f3rias das duas coloca\u00e7\u00f5es em algo coeso e relacion\u00e1vel.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>Resultado<\/strong>: A s\u00edntese de mapas geralmente melhora quanto mais mapas fazemos, portanto, pr\u00e1tica (supervisionada?) \u00e9 essencial. Nossos clientes precisam ouvir o produto final de nossa s\u00edntese, n\u00e3o nosso processo de pensamento.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><strong>\u00a0<\/strong><span style=\"color: #800000;\"><strong>Conversa e escuta<\/strong><\/span><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><span style=\"color: #000000;\">Devemos lembrar que uma consulta n\u00e3o \u00e9 uma palestra. O astr\u00f3logo pode facilmente perder a aten\u00e7\u00e3o de seus clientes quando faz um mon\u00f3logo sobre a narrativa do mapa sem verificar com os clientes se eles est\u00e3o no caminho certo. Sugere-se fazer uma pausa na conversa depois de no m\u00e1ximo 10-15 minutos e perguntar aos clientes se eles se identificam com os pontos levantados, ou se t\u00eam algo para compartilhar. Isto tamb\u00e9m ajuda o astr\u00f3logo avaliar se os clientes entenderam o que foi dito, da maneira que foi pretendida.<\/span><\/p>\n<p><span style=\"color: #000000;\">Por outro lado, os clientes podem ir a uma consulta astrol\u00f3gica e compartilharem suas hist\u00f3rias em detalhes elaborados, tirando um tempo significativo da consulta. Embora possa ser \u00fatil servir como um ouvinte e deixar o cliente desabafar, o que chega at\u00e9 n\u00f3s como queixa \u00e9 que estes clientes comumente expressar\u00e3o insatisfa\u00e7\u00e3o porque foram os que mais falaram e o astr\u00f3logo n\u00e3o forneceu novos conhecimentos a partir de seu mapa. \u00c9 o papel do astr\u00f3logo manter os limites, ent\u00e3o com habilidade procure direcionar a conversa de volta para o mapa, ao menos que o cliente insista em continuar a falar.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>Resultado<\/strong>: O astr\u00f3logo \u00e9 quem est\u00e1 encarregado de conduzir a consulta, e deve evitar ser influenciado por um cliente que est\u00e1 meio perdendo o rumo. As sess\u00f5es de astrologia s\u00e3o geralmente sess\u00f5es \u00fanicas, portanto os clientes normalmente t\u00eam expectativa de receberem orienta\u00e7\u00e3o por seus honor\u00e1rios.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff6600;\">DISCUTINDO POSICIONAMENTOS DIF\u00cdCEIS DOS MAPAS<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">Quando sentimos a necessidade de destrinchar uma configura\u00e7\u00e3o desafiadora do mapa ou falar sobre um tr\u00e2nsito dif\u00edcil, \u00e9 preciso ter consci\u00eancia para comunicar tais informa\u00e7\u00f5es de forma eficaz. O princ\u00edpio orientador \u00e9 que <strong>n\u00f3s estamos l\u00e1 para ajudar nossos clientes, n\u00e3o para mostrar o quanto sabemos<\/strong>. A primeira pergunta \u00e9 se \u00e9 necess\u00e1rio e \u00fatil para nosso cliente levantar tal quest\u00e3o dif\u00edcil; nem tudo no mapa precisa ser discutido, apenas o que \u00e9 relevante e \u00fatil. Em primeiro lugar, ser\u00e1 que precisamos mexer naquilo?<\/span><\/p>\n<p><span style=\"color: #000000;\">Se o astr\u00f3logo concluir que destrinchar a configura\u00e7\u00e3o dif\u00edcil atender\u00e1 o cliente, \u00e9 importante medir a receptividade do cliente e fazer isso pouco a pouco. Fazer perguntas pode ser um bom ponto de partida. Vamos usar um exemplo de um cliente com uma <em>conjun\u00e7\u00e3o<\/em> <em>Lua\/Plut\u00e3o natal<\/em> <em>que em breve ser\u00e1 desafiada por Saturno<\/em>. O astr\u00f3logo pode perguntar sobre seu atual status familiar: <em>&#8220;Voc\u00ea \u00e9 casado? Voc\u00ea mant\u00e9m contato com seus pais? Voc\u00ea sente alguma frustra\u00e7\u00e3o em sua vida familiar?&#8221;<\/em> Se o cliente responder: <em>&#8220;Estou no relacionamento melhor e mais amoroso que existe&#8221;<\/em>, ou por outro lado, <em>&#8220;Estou \u00e0 beira de um div\u00f3rcio&#8221;<\/em>, tudo isto poder\u00e1 fornecer contexto para o astr\u00f3logo abordar este tr\u00e2nsito que se aproxima.<\/span><\/p>\n<p><span style=\"color: #000000;\">A astrologia pode servir como uma ferramenta preventiva. O motivo pelo qual podemos querer abordar posicionamentos dif\u00edceis \u00e9 equipar nosso cliente com estrat\u00e9gias eficazes para tirar o melhor proveito da situa\u00e7\u00e3o, e talvez minimizar ferimentos. Eu pessoalmente sou da opini\u00e3o que os planetas n\u00e3o est\u00e3o &#8220;l\u00e1 fora para nos pegar,&#8221; da mesma forma que o inverno n\u00e3o existe para nos fazer sentir terrivelmente com frio. Ciclos planet\u00e1rios, por mais desafiadores que sejam, refletem o desdobramento de processos naturais universais; com prepara\u00e7\u00e3o e compreens\u00e3o, estas influ\u00eancias podem ser alquimizadas em mudan\u00e7as ben\u00e9ficas em nossas trajet\u00f3rias de vida.<\/span><\/p>\n<p><span style=\"color: #000000;\">O astr\u00f3logo n\u00e3o deve mentir aos seus clientes para faz\u00ea-los se sentirem bem. N\u00f3s preferimos ser o portador de boas not\u00edcias, mas a honestidade \u00e9 um verdadeiro servi\u00e7o, <strong>com a condi\u00e7\u00e3o<\/strong> que tal honestidade esteja sintonizada com a receptividade dos clientes<em>. &#8220;Este pode ser um momento para reavaliar alguns de seus apegos, pode ser um momento para ser mais firme com seus limites, ipode ser um momento para aceitar suas vulnerabilidades e avaliar se voc\u00ea pode contar com um bom suporte&#8221;.<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\">Discutir a quest\u00e3o desafiadora em pequenas doses pode ajudar o cliente a processar melhor. Se houver mais material a ser processado, talvez seja necess\u00e1rio marcar uma outra sess\u00e3o para acompanhamento.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>Resultado<\/strong>: Os astr\u00f3logos frequentemente abordam quest\u00f5es e problemas muito delicados em uma consulta, portanto vale a pena considerar que um cliente precise processar essas din\u00e2micas gradualmente. Alguns clientes alegar\u00e3o que querem saber tudo, e que o astr\u00f3logo n\u00e3o deva esconder nada deles. Ainda assim, \u00e9 dever do astr\u00f3logo avaliar at\u00e9 onde eles realmente podem ou devem ir.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff6600;\"><strong>DECLARA\u00c7\u00d5ES DETERMIN\u00cdSTICAS<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">Em minha experi\u00eancia como profissional e com envolvimento com a comunidade, eu nunca me deparei com alguma t\u00e9cnica ou abordagem da astrologia que j\u00e1 tenha sido 100 por cento confi\u00e1vel. Nenhuma t\u00e9cnica preditiva provou nunca ter falhado, seja usando M\u00e9todos V\u00e9dicos, Tradicionais ou Human\u00edsticos de interpreta\u00e7\u00e3o. A astrologia revela muita coisa, mas nunca tudo, e isso deve manter-nos humildes.<\/span><\/p>\n<p><span style=\"color: #000000;\">Portanto, nenhum astr\u00f3logo pode fazer declara\u00e7\u00f5es ou previs\u00f5es absolutas sem o benef\u00edcio da d\u00favida. Certamente existem vezes em que vemos maiores probabilidades de certos resultados, tendo em mente que a vida continua nos surpreendendo.<\/span><\/p>\n<p><span style=\"color: #000000;\">Declara\u00e7\u00f5es tais como <em>&#8220;voc\u00ea nunca vai se casar,&#8221;<\/em> ou <em>&#8220;voc\u00ea ter\u00e1 uma doen\u00e7a em 2019,&#8221;<\/em> ou, ao contr\u00e1rio, <em>&#8220;voc\u00ea tem garantia de sucesso neste neg\u00f3cio&#8221;<\/em>, pode ser muito prejudicial, n\u00e3o s\u00f3 porque elas podem ser angustiantes ou ent\u00e3o gerar altas expectativas, mas porque o astr\u00f3logo n\u00e3o pode realmente reivindicar tal autoridade.<\/span><\/p>\n<p><span style=\"color: #000000;\">Reformulando estas declara\u00e7\u00f5es em uma linguagem mais sugestiva seria importante:<\/span><\/p>\n<p><span style=\"color: #000000;\"><em>\u201c Vejamos algumas inibi\u00e7\u00f5es em sua capacidade de confiar em relacionamentos&#8221;<\/em><\/span><br \/>\n<span style=\"color: #000000;\">ou<\/span><br \/>\n<span style=\"color: #000000;\"><em>&#8220;J\u00e1 que voc\u00ea est\u00e1 sob muito estresse de trabalho, seria uma boa ideia fazer um check-up e exames de sangue&#8221;<\/em> ou <em>&#8220;H\u00e1 altas probabilidades de resultados promissores em seus neg\u00f3cios&#8221;<\/em>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>Resultado<\/strong>: Sabemos haver um certo orgulho em se querer adivinhar ou em se fazer declara\u00e7\u00f5es determin\u00edsticas e absolutas por querermos prometer fortuna para poder fazer nosso cliente feliz ou por querermos demonstrar nossas habilidades. Reconhecendo nossa possibilidade de falha \u00e9 o que nos tornar\u00e1 praticantes mais confi\u00e1veis.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff6600;\"><strong>DECLARA\u00c7\u00d5ES GEN\u00c9RICAS \u201cM\u00c1GICAS\u201d<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">Como mencionado anteriormente, preferimos ser portadores de boas not\u00edcias, e muitas vezes os astr\u00f3logos, especialmente aqueles que tenham uma abordagem humanista\/moderna, podem for\u00e7ar uma vis\u00e3o positiva em tudo at\u00e9 um ponto em que n\u00e3o prestem um verdadeiro servi\u00e7o ao cliente.<\/span><\/p>\n<p><span style=\"color: #000000;\">Voltando a discuss\u00e3o do Tr\u00e2nsito Dif\u00edcil, dizendo a um cliente que eles ter\u00e3o <em>&#8220;uma transforma\u00e7\u00e3o surpreendente&#8221;<\/em> uma vez que Saturno em tr\u00e2nsito est\u00e1 vindo para se opor a sua conjun\u00e7\u00e3o Lua\/Plut\u00e3o, ou ainda mais genericamente, que <em>&#8220;tudo vai ser \u00f3timo&#8221;<\/em>, ou <em>&#8220;apenas se desapegue&#8221;<\/em>, proporcionam uma falsa sensa\u00e7\u00e3o de conforto. Algumas dessas declara\u00e7\u00f5es gen\u00e9ricas se aplicam frequentemente a todos em todas as situa\u00e7\u00f5es, e enquanto eles servirem como sabedoria convencional, poder\u00e1 n\u00e3o atender adequadamente \u00e0s preocupa\u00e7\u00f5es reais do cliente. Fornecer orienta\u00e7\u00f5es mais espec\u00edficas, pertinentes \u00e0 quest\u00e3o, ser\u00e1 mais \u00fatil para o cliente.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>Resultado<\/strong>: Acolher somente o cliente n\u00e3o substitui a capacita\u00e7\u00e3o<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><span style=\"color: #ff6600;\"><strong>CONTEXTO S\u00d3CIO-CULTURAL<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">Nesta era da Internet, muitos astr\u00f3logos s\u00e3o capazes de expandir sua pr\u00e1tica al\u00e9m dos limites de seu pr\u00f3prio ambiente cultural. Isto realmente acontece em uma pr\u00e1tica internacional, mas com tal expans\u00e3o, considera\u00e7\u00f5es importantes precisam ser abordadas. Ler um mapa para algu\u00e9m que vive no Oriente M\u00e9dio ser\u00e1 diferente de uma consulta para algu\u00e9m que vive na Escandin\u00e1via. Por mais mundanos que sejam nossos clientes, os diferentes valores e \u00eanfases passam pelo condicionamento cultural. Estas considera\u00e7\u00f5es culturais precedem o mapa astrol\u00f3gico. N\u00e3o h\u00e1 um livro de receitas para nos ensinar a navegar nas in\u00fameras culturas, por isso pode ser \u00fatil fazer perguntas e descobrir diretamente de nossos clientes o que seria importante para eles.<\/span><\/p>\n<p><span style=\"color: #000000;\">Portanto, precisamos verificar nossos preconceitos pr\u00f3prios. Por exemplo, se o astr\u00f3logo \u00e9 uma pessoa que acredita firmemente na liberdade individual e faz uma leitura para uma pessoa gay que n\u00e3o pretende sair do arm\u00e1rio, existe uma necessidade de maior compreens\u00e3o do contexto do cliente. Se o astr\u00f3logo se sentir confuso com o estilo de vida de seu cliente, pode ser melhor encaminh\u00e1-lo para outra pessoa.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>Resultado<\/strong>: O mapa astrol\u00f3gico n\u00e3o mostra o g\u00eanero ou a cultura da pessoa, ou mesmo se o mapa for para um ser humano ou um animal. Portanto, fazendo perguntas e descobrindo algumas informa\u00e7\u00f5es do passado sobre o cliente \u00e9 essencial para se estabelecer um contexto para o mapa.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff6600;\"><strong>CONCLUS\u00c3O<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">N\u00e3o importa qu\u00e3o experiente se possa ser, a autocr\u00edtica nos tornar\u00e1 melhores astr\u00f3logos. <strong>Para mais informa\u00e7\u00f5es sobre os Programas de T\u00e9cnicas de Atendimento e Grupos em Pares do OPA, visite: https:\/\/www.opaastrology.org\/opa-certification\/certification-with-opa<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong><em>Maurice Fernandez<\/em><\/strong><em>, autor dos livros: \u201cNetuno\u201d, \u201cA Casa XII e Peixes\u201d (Nova Edi\u00e7\u00e3o), e \u201cAstrologia e a Evolu\u00e7\u00e3o da Consci\u00eancia &#8211; Volume Um\u201d, \u00e9 um consultor e professor l\u00edder de Astrologia Evolutiva, atualmente sediada no Arizona. Maurice serviu como o presidente para \u201cThe Organization of Professional Astrology (OPA)\u201d por tr\u00eas mandatos &#8211; 2014-2020. Ele dirige um programa de certifica\u00e7\u00e3o profissional, apoiando, incentivando e criando uma futura gera\u00e7\u00e3o de astr\u00f3logos. <strong>www.mauricefernandez.com<\/strong><\/em><\/span><\/p>\n<p><span style=\"color: #000000;\"><em>Facebook: <strong>https:\/\/www.facebook.com\/maurice astrologia\/<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desafios comuns nas Consultas Astrol\u00f3gicas por Maurice Fernandez &nbsp; A Astrologia tem capturado de forma irrevers\u00edvel os cora\u00e7\u00f5es e mentes de muitos de n\u00f3s, muitas vezes de maneiras inesperadas. &nbsp; Foi um livro sobre signo solar, uma leitura transformadora, ou<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8850","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DESAFIOS COMUNS EM CONSULTA - C.E.A.P.<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DESAFIOS COMUNS EM CONSULTA - C.E.A.P.\" \/>\n<meta property=\"og:description\" content=\"Desafios comuns nas Consultas Astrol\u00f3gicas por Maurice Fernandez &nbsp; A Astrologia tem capturado de forma irrevers\u00edvel os cora\u00e7\u00f5es e mentes de muitos de n\u00f3s, muitas vezes de maneiras inesperadas. &nbsp; Foi um livro sobre signo solar, uma leitura transformadora, ou\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astroceap.com.br\/ceap\/desafios-comuns-em-consulta\/\" \/>\n<meta property=\"og:site_name\" content=\"C.E.A.P.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/astroceap\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-29T20:10:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-29T20:16:27+00:00\" \/>\n<meta name=\"author\" content=\"M\u00e1rcia Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:site\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00e1rcia Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/desafios-comuns-em-consulta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/desafios-comuns-em-consulta\\\/\"},\"author\":{\"name\":\"M\u00e1rcia Ferreira\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/71c3b7859d3eb1da9042ec5ff95f0f19\"},\"headline\":\"DESAFIOS COMUNS EM CONSULTA\",\"datePublished\":\"2021-04-29T20:10:53+00:00\",\"dateModified\":\"2021-04-29T20:16:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/desafios-comuns-em-consulta\\\/\"},\"wordCount\":2601,\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/desafios-comuns-em-consulta\\\/\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/desafios-comuns-em-consulta\\\/\",\"name\":\"DESAFIOS COMUNS EM CONSULTA - C.E.A.P.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\"},\"datePublished\":\"2021-04-29T20:10:53+00:00\",\"dateModified\":\"2021-04-29T20:16:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/desafios-comuns-em-consulta\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/desafios-comuns-em-consulta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/desafios-comuns-em-consulta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DESAFIOS COMUNS EM CONSULTA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"name\":\"C.E.A.P.\",\"description\":\"Centro de Estudos de Astrologia Psicol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\",\"name\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"contentUrl\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"width\":140,\"height\":174,\"caption\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/astroceap\\\/\",\"https:\\\/\\\/x.com\\\/astrologiaceap\",\"https:\\\/\\\/www.instagram.com\\\/ceap.astrologia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDsKeXx5S7f2xoPUxNpARSQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/71c3b7859d3eb1da9042ec5ff95f0f19\",\"name\":\"M\u00e1rcia Ferreira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"caption\":\"M\u00e1rcia Ferreira\"},\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/author\\\/marcia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DESAFIOS COMUNS EM CONSULTA - C.E.A.P.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"DESAFIOS COMUNS EM CONSULTA - C.E.A.P.","og_description":"Desafios comuns nas Consultas Astrol\u00f3gicas por Maurice Fernandez &nbsp; A Astrologia tem capturado de forma irrevers\u00edvel os cora\u00e7\u00f5es e mentes de muitos de n\u00f3s, muitas vezes de maneiras inesperadas. &nbsp; Foi um livro sobre signo solar, uma leitura transformadora, ou","og_url":"https:\/\/astroceap.com.br\/ceap\/desafios-comuns-em-consulta\/","og_site_name":"C.E.A.P.","article_publisher":"https:\/\/www.facebook.com\/astroceap\/","article_published_time":"2021-04-29T20:10:53+00:00","article_modified_time":"2021-04-29T20:16:27+00:00","author":"M\u00e1rcia Ferreira","twitter_card":"summary_large_image","twitter_creator":"@astrologiaceap","twitter_site":"@astrologiaceap","twitter_misc":{"Escrito por":"M\u00e1rcia Ferreira","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astroceap.com.br\/ceap\/desafios-comuns-em-consulta\/#article","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/desafios-comuns-em-consulta\/"},"author":{"name":"M\u00e1rcia Ferreira","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/71c3b7859d3eb1da9042ec5ff95f0f19"},"headline":"DESAFIOS COMUNS EM CONSULTA","datePublished":"2021-04-29T20:10:53+00:00","dateModified":"2021-04-29T20:16:27+00:00","mainEntityOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/desafios-comuns-em-consulta\/"},"wordCount":2601,"publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"articleSection":["Uncategorized"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/astroceap.com.br\/ceap\/desafios-comuns-em-consulta\/","url":"https:\/\/astroceap.com.br\/ceap\/desafios-comuns-em-consulta\/","name":"DESAFIOS COMUNS EM CONSULTA - C.E.A.P.","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/#website"},"datePublished":"2021-04-29T20:10:53+00:00","dateModified":"2021-04-29T20:16:27+00:00","breadcrumb":{"@id":"https:\/\/astroceap.com.br\/ceap\/desafios-comuns-em-consulta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astroceap.com.br\/ceap\/desafios-comuns-em-consulta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/astroceap.com.br\/ceap\/desafios-comuns-em-consulta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/astroceap.com.br\/ceap\/"},{"@type":"ListItem","position":2,"name":"DESAFIOS COMUNS EM CONSULTA"}]},{"@type":"WebSite","@id":"https:\/\/astroceap.com.br\/ceap\/#website","url":"https:\/\/astroceap.com.br\/ceap\/","name":"C.E.A.P.","description":"Centro de Estudos de Astrologia Psicol\u00f3gica","publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astroceap.com.br\/ceap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/astroceap.com.br\/ceap\/#organization","name":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica","url":"https:\/\/astroceap.com.br\/ceap\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/","url":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","contentUrl":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","width":140,"height":174,"caption":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/astroceap\/","https:\/\/x.com\/astrologiaceap","https:\/\/www.instagram.com\/ceap.astrologia\/","https:\/\/www.youtube.com\/channel\/UCDsKeXx5S7f2xoPUxNpARSQ"]},{"@type":"Person","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/71c3b7859d3eb1da9042ec5ff95f0f19","name":"M\u00e1rcia Ferreira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","caption":"M\u00e1rcia Ferreira"},"url":"https:\/\/astroceap.com.br\/ceap\/author\/marcia\/"}]}},"_links":{"self":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/8850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/comments?post=8850"}],"version-history":[{"count":4,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/8850\/revisions"}],"predecessor-version":[{"id":8854,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/8850\/revisions\/8854"}],"wp:attachment":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media?parent=8850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/categories?post=8850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/tags?post=8850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}