{"id":8985,"date":"2022-04-12T15:38:28","date_gmt":"2022-04-12T18:38:28","guid":{"rendered":"http:\/\/astroceap.com.br\/ceap\/?p=8985"},"modified":"2022-04-12T17:35:36","modified_gmt":"2022-04-12T20:35:36","slug":"conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor","status":"publish","type":"post","link":"https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/","title":{"rendered":"Conjun\u00e7\u00e3o J\u00fapiter Netuno em Peixes! A grande t\u00f4nica de 2022! Entenda melhor"},"content":{"rendered":"<p class=\"p1\"><img decoding=\"async\" class=\"size-medium wp-image-8986 aligncenter lazyload\" data-src=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/04\/jupiter-conj-netuno-feed-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" data-srcset=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/04\/jupiter-conj-netuno-feed-300x300.jpg 300w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/04\/jupiter-conj-netuno-feed-1024x1024.jpg 1024w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/04\/jupiter-conj-netuno-feed-150x150.jpg 150w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/04\/jupiter-conj-netuno-feed-768x768.jpg 768w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/04\/jupiter-conj-netuno-feed-230x230.jpg 230w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/04\/jupiter-conj-netuno-feed-330x330.jpg 330w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/04\/jupiter-conj-netuno-feed.jpg 1080w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\">Estamos tendo o in\u00edcio de um novo ciclo muito importante neste momento, quer n\u00f3s estejamos percebendo-o ou n\u00e3o! E este novo ciclo nos impacta a todos coletivamente, com a conjun\u00e7\u00e3o exata entre J\u00fapiter e Netuno aos 23 graus de Peixes, em 12\/04\/22! A \u00faltima vez que estes 02 planetas se encontraram foi h\u00e1 13 anos atr\u00e1s ( mas em outro signo, em Aqu\u00e1rio ) e tamb\u00e9m considerando-se que somente voltar\u00e3o a se encontrar novamente em Peixes em 2188, quando nenhum de n\u00f3s estar\u00e1 aqui para testemunhar este encontro, s\u00f3 por a\u00ed podemos entender a magnitude deste ciclo entre estes dois planetas, e tal acontecimento c\u00f3smico e hist\u00f3rico est\u00e1 se dando agora e ao longo de 2022!<\/p>\n<p class=\"p1\">Os ciclos na astrologia mundial s\u00e3o eventos de grande magnitude celeste e estas grandes conjun\u00e7\u00f5es, como assim s\u00e3o chamadas, reverberam na terra atrav\u00e9s de eventos tamb\u00e9m de grande magnitude, portanto estamos sob o impacto de um novo ciclo que durar\u00e1 166 anos!<\/p>\n<p class=\"p1\">Interessante notarmos que tanto Netuno como J\u00fapiter s\u00e3o regente e co-regente de Peixes, respectivamente, e o fato de ambos encontrarem-se em seu signo de reg\u00eancia, nos traz conota\u00e7\u00f5es positivas com certeza, mas tamb\u00e9m poder\u00e3o haver alguns desafios.<\/p>\n<p class=\"p1\">Ambos os planetas representam o lado transcendente e abstrato da exist\u00eancia, onde nos conectamos com esferas intang\u00edveis e n\u00e3o materiais. \u00c9 atrav\u00e9s destes 02 planetas que podemos sair dessa esfera materialista da vida, nos conectarmos com algo superior ou alguma divindade, seja qual for a que queiramos adotar, que nos possibilite acessar algo maior do que n\u00f3s, uma for\u00e7a criadora, mesmo que muitas vezes nem saibamos explicar.<\/p>\n<p>Atrav\u00e9s destes dois planetas podemos acessar uma orienta\u00e7\u00e3o mais ligada ao SELF e n\u00e3o ao EGO, como dizia Jung, pois a orienta\u00e7\u00e3o eg\u00f3ica quer determinar e controlar as situa\u00e7\u00f5es e submeter tudo \u00e0 vontade pessoal, mas nesta outra conex\u00e3o nos permitimos entender os ciclos e fluxos muito maiores que n\u00f3s e passamos a ter uma humildade e aceita\u00e7\u00e3o em seguir este fluxo.<br \/>\nAl\u00e9m disso, \u00e9 atrav\u00e9s de Netuno e J\u00fapiter na Astrologia que podemos acessar as qualidades de empatia, compaix\u00e3o, generosidade e cuidado com o pr\u00f3ximo, uma entrega desprendida e uma possibilidade de a\u00e7\u00e3o altru\u00edsta e que seja para o benef\u00edcio coletivo. Netuno nos leva a sonhar, a romancear, a idealizar.<\/p>\n<p>Ser\u00e1 tamb\u00e9m um novo ciclo ligado a cinema e m\u00fasica, quando haver\u00e3o novas tend\u00eancias nessas \u00e1reas e um<span class=\"Apple-converted-space\">&nbsp; <\/span>aumento de patroc\u00ednios em obras culturais e intelectuais; a arte e a cultura sendo mais valorizadas, nos possibilitando o sonhar.<\/p>\n<p class=\"p1\">Socialismo e assistencialismo \u00e0s classes menos favorecidas tendem a ser alvo de aten\u00e7\u00e3o e investimentos tamb\u00e9m.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n<p class=\"p1\">A \u00e1rea m\u00e9dica tamb\u00e9m ser\u00e1 muito favorecida com esta conjun\u00e7\u00e3o, com o incremento de descobertas que contribuam para a sa\u00fade da popula\u00e7\u00e3o, como por exemplo a descoberta de novas vacinas, ou o barateamento dos pre\u00e7os dos rem\u00e9dios. J\u00e1 no que diz respeito \u00e0 pandemia, esta tend\u00eancia poder\u00e1 se expressar do lado positivo no que se refere \u00e0 globaliza\u00e7\u00e3o e partilha justa de medicamentos e vacinas, pois a consci\u00eancia de que estamos todos no mesmo barco ser\u00e1 cada vez mais forte e de que nada adiantar\u00e1 um pa\u00eds rico ter vacinas se um pa\u00eds pobre n\u00e3o as tiver.<\/p>\n<p class=\"p1\">Poderemos ter tamb\u00e9m uma busca maior de misticismo, espiritualidade, religiosidade sob formas de encontros coletivos, retiros junto \u00e0 natureza, busca de significados superiores e filos\u00f3ficos como tamb\u00e9m um incremento de viagens internacionais e mar\u00edtimas. Discuss\u00f5es sobre drogas legais e ilegais ou sobre a libera\u00e7\u00e3o da maconha medicinal, por exemplo, poder\u00e3o estar mais presentes.<\/p>\n<p class=\"p1\">Pelas leis do sincretismo em que os significados arquet\u00edpicos se fundem, Netuno corresponde a Poseidon da Mitologia Grega, o deus dos mares e oceanos, e J\u00fapiter ao deus dos c\u00e9us. Eram irm\u00e3os, filhos de Cronos. Zeus escapou de ser engolido pelo pai, o fez regurgitar e assim p\u00f4de salvar os irm\u00e3os. Dividiram os reinos e cada um respeitou o territ\u00f3rio do outro. Portanto, este tr\u00e2nsito nos fala de fraternidade, de igualdade, de respeito m\u00fatuo e n\u00e3o \u00e0 toa neste momento est\u00e1 em voga o termo \u201csororidade\u201d, nos lembrando da import\u00e2ncia do respeito e solidariedade entre as mulheres. Um conceito que surge neste momento e que veio para ficar.<\/p>\n<p class=\"p1\">Se estes dois arqu\u00e9tipos por um lado nos acrescentam estes significados existenciais maiores e que nos abrem para novas possibilidades de realidade de forma positiva, por outro lado tamb\u00e9m podem trazer exageros de toda ordem e uma falta de senso de realidade e de \u201cp\u00e9 no ch\u00e3o\u201d. Ambos tamb\u00e9m n\u00e3o querem saber de restri\u00e7\u00f5es ou de serem limitados e buscam muita expans\u00e3o, a do tipo \u201co c\u00e9u \u00e9 o limite\u201d.<\/p>\n<p class=\"p1\">Os gregos da Antiguidade empregavam o termo hubris ou hybris para designar \u201ctudo o que passa da medida, descomedimento\u201d, o que com frequ\u00eancia terminaria em puni\u00e7\u00e3o. Se h\u00e1 um perigo neste ciclo de J\u00fapiter com Netuno em Peixes, seria exatamente este, o pecado da hubris ou hybris, o da falta de limites.<\/p>\n<p class=\"p1\">Do lado mais desafiador, portanto, poder\u00e1 haver um otimismo exagerado, fantasias e utopias. Cuidado com excessos de idealiza\u00e7\u00f5es de toda ordem, cren\u00e7as em salvadores, milagres ou solu\u00e7\u00f5es imediatistas e m\u00e1gicas dos problemas. Esta grande conjun\u00e7\u00e3o est\u00e1 chegando num momento em que o mundo est\u00e1 sedento por ouvir not\u00edcias boas, como a elimina\u00e7\u00e3o definitiva do Covid e de outros problemas graves, e assim, poder\u00e1 haver uma tend\u00eancia em se querer acreditar em qualquer fake news que seja, para trazer esse desejo libertador.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n<p class=\"p1\">Mais do que nunca, teremos que enfrentar as fake news, assim como tamb\u00e9m nos mostra o mapa de ingresso do equin\u00f3cio ( veja o post<span class=\"Apple-converted-space\">&nbsp; <\/span>anterior).<\/p>\n<p class=\"p1\">Poss\u00edveis desastres naturais envolvendo \u00e1gua, inunda\u00e7\u00f5es, tsunamis ou ainda a crise h\u00eddrica mundial poder\u00e1 ganhar destaque.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n<p class=\"p1\">E o que fazer a n\u00edvel individual?<\/p>\n<p class=\"p1\">Que possamos aproveitar este tr\u00e2nsito para fortalecermos nossa busca transcendental, tendo f\u00e9 e acreditando num poder superior que poder\u00e1 trazer maior compaix\u00e3o e empatia para a humanidade! Esta empatia poder\u00e1 nos mover a querer atuar a n\u00edvel coletivo, ajudando os necessitados neste momento mundial t\u00e3o dif\u00edcil. Que possamos nos conectar com o lado da generosidade, da dedica\u00e7\u00e3o para com o pr\u00f3ximo, da compassividade, da entrega e que possa trazer benef\u00edcios ao coletivo. Por outro lado, que saibamos n\u00e3o nos deixar levar por comportamentos de escapismo, de nega\u00e7\u00e3o da realidade, de enganos e fraudes e de confus\u00f5es em qualquer n\u00edvel, e principalmente, da necessidade de precisar acreditar em qualquer not\u00edcia que nos traga al\u00edvio!<\/p>\n<p class=\"p1\">Que saibamos ter o discernimento correto para separar o que seja real do ilus\u00f3rio! Um \u00f3timo novo ciclo para voc\u00ea!<\/p>\n<p class=\"p1\">#sororidade #fraternidade #j\u00fapiter #netuno #conjun\u00e7\u00e3ojupiternetunoempeixes #ciclo #irmandade #vacinas #espiritualidade #compaix\u00e3o #self #jung<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Estamos tendo o in\u00edcio de um novo ciclo muito importante neste momento, quer n\u00f3s estejamos percebendo-o ou n\u00e3o! E este novo ciclo nos impacta a todos coletivamente, com a conjun\u00e7\u00e3o exata entre J\u00fapiter e Netuno aos 23 graus de<\/p>\n","protected":false},"author":2,"featured_media":8986,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[23],"tags":[124,128,123,127,120,125,72,121,122,129,119,126],"class_list":["post-8985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-ciclo","tag-compaixao","tag-conjuncaoupiternetunoempeixes","tag-espiritualidade","tag-fraternidade","tag-irmandade","tag-jung","tag-jupiter","tag-netuno","tag-self","tag-sororidade","tag-vacinas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conjun\u00e7\u00e3o J\u00fapiter Netuno em Peixes! A grande t\u00f4nica de 2022! Entenda melhor - C.E.A.P.<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conjun\u00e7\u00e3o J\u00fapiter Netuno em Peixes! A grande t\u00f4nica de 2022! Entenda melhor - C.E.A.P.\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Estamos tendo o in\u00edcio de um novo ciclo muito importante neste momento, quer n\u00f3s estejamos percebendo-o ou n\u00e3o! E este novo ciclo nos impacta a todos coletivamente, com a conjun\u00e7\u00e3o exata entre J\u00fapiter e Netuno aos 23 graus de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/\" \/>\n<meta property=\"og:site_name\" content=\"C.E.A.P.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/astroceap\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-12T18:38:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-12T20:35:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/04\/jupiter-conj-netuno-feed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00e1rcia Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:site\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00e1rcia Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\\\/\"},\"author\":{\"name\":\"M\u00e1rcia Ferreira\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/71c3b7859d3eb1da9042ec5ff95f0f19\"},\"headline\":\"Conjun\u00e7\u00e3o J\u00fapiter Netuno em Peixes! A grande t\u00f4nica de 2022! Entenda melhor\",\"datePublished\":\"2022-04-12T18:38:28+00:00\",\"dateModified\":\"2022-04-12T20:35:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\\\/\"},\"wordCount\":1210,\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/jupiter-conj-netuno-feed.jpg\",\"keywords\":[\"ciclo\",\"compaix\u00e3o\",\"conjun\u00e7\u00e3oupiternetunoempeixes\",\"espiritualidade\",\"fraternidade\",\"irmandade\",\"Jung\",\"j\u00fapiter\",\"netuno\",\"self\",\"sororidade\",\"vacinas\"],\"articleSection\":[\"BLOG\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\\\/\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\\\/\",\"name\":\"Conjun\u00e7\u00e3o J\u00fapiter Netuno em Peixes! A grande t\u00f4nica de 2022! Entenda melhor - C.E.A.P.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/jupiter-conj-netuno-feed.jpg\",\"datePublished\":\"2022-04-12T18:38:28+00:00\",\"dateModified\":\"2022-04-12T20:35:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/jupiter-conj-netuno-feed.jpg\",\"contentUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/jupiter-conj-netuno-feed.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conjun\u00e7\u00e3o J\u00fapiter Netuno em Peixes! A grande t\u00f4nica de 2022! Entenda melhor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"name\":\"C.E.A.P.\",\"description\":\"Centro de Estudos de Astrologia Psicol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\",\"name\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"contentUrl\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"width\":140,\"height\":174,\"caption\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/astroceap\\\/\",\"https:\\\/\\\/x.com\\\/astrologiaceap\",\"https:\\\/\\\/www.instagram.com\\\/ceap.astrologia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDsKeXx5S7f2xoPUxNpARSQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/71c3b7859d3eb1da9042ec5ff95f0f19\",\"name\":\"M\u00e1rcia Ferreira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"caption\":\"M\u00e1rcia Ferreira\"},\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/author\\\/marcia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conjun\u00e7\u00e3o J\u00fapiter Netuno em Peixes! A grande t\u00f4nica de 2022! Entenda melhor - C.E.A.P.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"Conjun\u00e7\u00e3o J\u00fapiter Netuno em Peixes! A grande t\u00f4nica de 2022! Entenda melhor - C.E.A.P.","og_description":"&nbsp; Estamos tendo o in\u00edcio de um novo ciclo muito importante neste momento, quer n\u00f3s estejamos percebendo-o ou n\u00e3o! E este novo ciclo nos impacta a todos coletivamente, com a conjun\u00e7\u00e3o exata entre J\u00fapiter e Netuno aos 23 graus de","og_url":"https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/","og_site_name":"C.E.A.P.","article_publisher":"https:\/\/www.facebook.com\/astroceap\/","article_published_time":"2022-04-12T18:38:28+00:00","article_modified_time":"2022-04-12T20:35:36+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/04\/jupiter-conj-netuno-feed.jpg","type":"image\/jpeg"}],"author":"M\u00e1rcia Ferreira","twitter_card":"summary_large_image","twitter_creator":"@astrologiaceap","twitter_site":"@astrologiaceap","twitter_misc":{"Escrito por":"M\u00e1rcia Ferreira","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/#article","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/"},"author":{"name":"M\u00e1rcia Ferreira","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/71c3b7859d3eb1da9042ec5ff95f0f19"},"headline":"Conjun\u00e7\u00e3o J\u00fapiter Netuno em Peixes! A grande t\u00f4nica de 2022! Entenda melhor","datePublished":"2022-04-12T18:38:28+00:00","dateModified":"2022-04-12T20:35:36+00:00","mainEntityOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/"},"wordCount":1210,"publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/04\/jupiter-conj-netuno-feed.jpg","keywords":["ciclo","compaix\u00e3o","conjun\u00e7\u00e3oupiternetunoempeixes","espiritualidade","fraternidade","irmandade","Jung","j\u00fapiter","netuno","self","sororidade","vacinas"],"articleSection":["BLOG"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/","url":"https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/","name":"Conjun\u00e7\u00e3o J\u00fapiter Netuno em Peixes! A grande t\u00f4nica de 2022! Entenda melhor - C.E.A.P.","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/#primaryimage"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/04\/jupiter-conj-netuno-feed.jpg","datePublished":"2022-04-12T18:38:28+00:00","dateModified":"2022-04-12T20:35:36+00:00","breadcrumb":{"@id":"https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/#primaryimage","url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/04\/jupiter-conj-netuno-feed.jpg","contentUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/04\/jupiter-conj-netuno-feed.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/astroceap.com.br\/ceap\/conjuncao-jupiter-netuno-em-peixes-a-grande-tonica-de-2022-entenda-melhor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/astroceap.com.br\/ceap\/"},{"@type":"ListItem","position":2,"name":"Conjun\u00e7\u00e3o J\u00fapiter Netuno em Peixes! A grande t\u00f4nica de 2022! Entenda melhor"}]},{"@type":"WebSite","@id":"https:\/\/astroceap.com.br\/ceap\/#website","url":"https:\/\/astroceap.com.br\/ceap\/","name":"C.E.A.P.","description":"Centro de Estudos de Astrologia Psicol\u00f3gica","publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astroceap.com.br\/ceap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/astroceap.com.br\/ceap\/#organization","name":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica","url":"https:\/\/astroceap.com.br\/ceap\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/","url":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","contentUrl":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","width":140,"height":174,"caption":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/astroceap\/","https:\/\/x.com\/astrologiaceap","https:\/\/www.instagram.com\/ceap.astrologia\/","https:\/\/www.youtube.com\/channel\/UCDsKeXx5S7f2xoPUxNpARSQ"]},{"@type":"Person","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/71c3b7859d3eb1da9042ec5ff95f0f19","name":"M\u00e1rcia Ferreira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","caption":"M\u00e1rcia Ferreira"},"url":"https:\/\/astroceap.com.br\/ceap\/author\/marcia\/"}]}},"_links":{"self":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/8985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/comments?post=8985"}],"version-history":[{"count":6,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/8985\/revisions"}],"predecessor-version":[{"id":8993,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/8985\/revisions\/8993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media\/8986"}],"wp:attachment":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media?parent=8985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/categories?post=8985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/tags?post=8985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}