{"id":9043,"date":"2022-06-28T17:29:54","date_gmt":"2022-06-28T20:29:54","guid":{"rendered":"http:\/\/astroceap.com.br\/ceap\/?p=9043"},"modified":"2022-07-08T16:14:12","modified_gmt":"2022-07-08T19:14:12","slug":"jung-e-a-astrologia-entrevista-para-editora-pensamento","status":"publish","type":"post","link":"https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/","title":{"rendered":"Entrevista para Editora Pensamento 3 &#8211; Sobre a tradu\u00e7\u00e3o do livro &#8220;Jung&#8217;s Studies in Astrology&#8221;"},"content":{"rendered":"<p><iframe title=\"VI\u0301DEO3_TRADUC\u0327A\u0303O DO LIVRO_JUN_22\" data-src=\"https:\/\/player.vimeo.com\/video\/725413190?h=4efd258c0d&amp;dnt=1&amp;app_id=122963\" width=\"710\" height=\"710\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p>Nesta entrevista explico sobre a minha recente tradu\u00e7\u00e3o do livro da Liz Greene \u201cJung\u2019s Studies in Astrology\u201d, para a qual fui convidada no in\u00edcio deste ano pelas Editoras Routledge de Londres e Pensamento do Brasil.<br \/>\nExplico nesta entrevista sobre a abordagem que Jung teve sobre a Astrologia, como a de uma linguagem arquet\u00edpica onde ele dizia, por exemplo, que os planetas eram como \u201cdeuses planet\u00e1rios\u201d que se relacionavam no mapa. O livro ser\u00e1 lan\u00e7ado no Brasil no segundo semestre com o prov\u00e1vel t\u00edtulo ( ainda n\u00e3o definido ) \u201cOs Estudos de Jung em Astrologia\u201d. Este livro \u00e9 um verdadeiro comp\u00eandio sobre o interesse de Jung em Astrologia durante toda sua vida: como era sua compreens\u00e3o sobre o assunto, quem foram seus astr\u00f3logos de refer\u00eancia, seu interesse em seu pr\u00f3prio mapa pessoal, a influ\u00eancia do Neoplatonismo em sua obra, como ele entendia as teias do destino e, principalmente, o quanto tudo isso teve influ\u00eancia no todo de sua obra. Liz Greene elaborou uma pesquisa minuciosa, com acesso aos arquivos pessoais de Jung atrav\u00e9s da permiss\u00e3o de membros de sua fam\u00edlia.<\/p>\n<p>Al\u00e9m disso, nesta entrevista tamb\u00e9m comento sobre o livro \u201cJung e a Astrologia\u201d da Kathleen Burt, que est\u00e1 sendo re-lan\u00e7ado no Brasil pela mesma editora neste momento!<\/p>\n<p>E se voc\u00ea gosta dessas interfaces entre psicologia, psicologia anal\u00edtica e astrologia, venha nos conhecer! Temos muitos cursos online, artigos e palestras com esta abordagem:\u00a0<a href=\"http:\/\/www.astrologiaceap.com.br\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer ugc\">www.astrologiaceap.com.br<\/a><br \/>\nOu siga-nos nas redes sociais: M\u00e1rcia Ferreira Astrologia Psicol\u00f3gica &#8211; FB e Youtube e Instagram:\u00a0<span class=\"atMention\" title=\"marciaferreira\">@marciaferreira<\/span>.astrologiaceap<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta entrevista explico sobre a minha recente tradu\u00e7\u00e3o do livro da Liz Greene \u201cJung\u2019s Studies in Astrology\u201d, para a qual fui convidada no in\u00edcio deste ano pelas Editoras Routledge de Londres e Pensamento do Brasil. Explico nesta entrevista sobre a<\/p>\n","protected":false},"author":2,"featured_media":9078,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[132],"tags":[115,114,133,37,39,136,74,138,82,84,44,139,72,137,40,144,43,134,38,135,140,42,142,141],"class_list":["post-9043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apresentacao","tag-cursodeastrologia","tag-cursosdeastrologia","tag-ascendente","tag-astrologia","tag-astrologia-psicologica","tag-astrologiapsicologica","tag-autoconhecimento","tag-casas-astrologicas","tag-curso-de-astrologia","tag-cursos-de-astrologia","tag-horoscopo","tag-infernoastral","tag-jung","tag-marciaferreira-ceap-psicologia","tag-mitologia","tag-mitologia-grega","tag-planetas","tag-previsoesastrologicas","tag-psicologia","tag-quatroelementos","tag-revolucaosolar","tag-signos","tag-sinastria","tag-transitosastrologicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entrevista para Editora Pensamento 3 - Sobre a tradu\u00e7\u00e3o do livro &quot;Jung&#039;s Studies in Astrology&quot; - C.E.A.P.<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista para Editora Pensamento 3 - Sobre a tradu\u00e7\u00e3o do livro &quot;Jung&#039;s Studies in Astrology&quot; - C.E.A.P.\" \/>\n<meta property=\"og:description\" content=\"Nesta entrevista explico sobre a minha recente tradu\u00e7\u00e3o do livro da Liz Greene \u201cJung\u2019s Studies in Astrology\u201d, para a qual fui convidada no in\u00edcio deste ano pelas Editoras Routledge de Londres e Pensamento do Brasil. Explico nesta entrevista sobre a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/\" \/>\n<meta property=\"og:site_name\" content=\"C.E.A.P.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/astroceap\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-28T20:29:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-08T19:14:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/Entrevista-para-Editora-Pensamento-3-\u2013-Sobre-a-traducao-do-livro-Jungs-Studies-in-Astrology.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"694\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00e1rcia Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:site\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00e1rcia Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/jung-e-a-astrologia-entrevista-para-editora-pensamento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/jung-e-a-astrologia-entrevista-para-editora-pensamento\\\/\"},\"author\":{\"name\":\"M\u00e1rcia Ferreira\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/71c3b7859d3eb1da9042ec5ff95f0f19\"},\"headline\":\"Entrevista para Editora Pensamento 3 &#8211; Sobre a tradu\u00e7\u00e3o do livro &#8220;Jung&#8217;s Studies in Astrology&#8221;\",\"datePublished\":\"2022-06-28T20:29:54+00:00\",\"dateModified\":\"2022-07-08T19:14:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/jung-e-a-astrologia-entrevista-para-editora-pensamento\\\/\"},\"wordCount\":292,\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/jung-e-a-astrologia-entrevista-para-editora-pensamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Entrevista-para-Editora-Pensamento-3-\u2013-Sobre-a-traducao-do-livro-Jungs-Studies-in-Astrology.jpeg\",\"keywords\":[\"#cursodeastrologia\",\"#cursosdeastrologia\",\"ascendente\",\"astrologia\",\"astrologia psicol\u00f3gica\",\"astrologiapsicologica\",\"autoconhecimento\",\"casas astrol\u00f3gicas\",\"curso de astrologia\",\"cursos de astrologia\",\"hor\u00f3scopo\",\"infernoastral\",\"Jung\",\"marciaferreira ceap psicologia\",\"mitologia\",\"mitologia grega\",\"planetas\",\"previsoesastrologicas\",\"psicologia\",\"quatroelementos\",\"revolucaosolar\",\"signos\",\"sinastria\",\"transitosastrologicos\"],\"articleSection\":[\"APRESENTA\u00c7\u00c3O\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/jung-e-a-astrologia-entrevista-para-editora-pensamento\\\/\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/jung-e-a-astrologia-entrevista-para-editora-pensamento\\\/\",\"name\":\"Entrevista para Editora Pensamento 3 - Sobre a tradu\u00e7\u00e3o do livro \\\"Jung's Studies in Astrology\\\" - C.E.A.P.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/jung-e-a-astrologia-entrevista-para-editora-pensamento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/jung-e-a-astrologia-entrevista-para-editora-pensamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Entrevista-para-Editora-Pensamento-3-\u2013-Sobre-a-traducao-do-livro-Jungs-Studies-in-Astrology.jpeg\",\"datePublished\":\"2022-06-28T20:29:54+00:00\",\"dateModified\":\"2022-07-08T19:14:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/jung-e-a-astrologia-entrevista-para-editora-pensamento\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/jung-e-a-astrologia-entrevista-para-editora-pensamento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/jung-e-a-astrologia-entrevista-para-editora-pensamento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Entrevista-para-Editora-Pensamento-3-\u2013-Sobre-a-traducao-do-livro-Jungs-Studies-in-Astrology.jpeg\",\"contentUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Entrevista-para-Editora-Pensamento-3-\u2013-Sobre-a-traducao-do-livro-Jungs-Studies-in-Astrology.jpeg\",\"width\":750,\"height\":694},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/jung-e-a-astrologia-entrevista-para-editora-pensamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista para Editora Pensamento 3 &#8211; Sobre a tradu\u00e7\u00e3o do livro &#8220;Jung&#8217;s Studies in Astrology&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"name\":\"C.E.A.P.\",\"description\":\"Centro de Estudos de Astrologia Psicol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\",\"name\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"contentUrl\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"width\":140,\"height\":174,\"caption\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/astroceap\\\/\",\"https:\\\/\\\/x.com\\\/astrologiaceap\",\"https:\\\/\\\/www.instagram.com\\\/ceap.astrologia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDsKeXx5S7f2xoPUxNpARSQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/71c3b7859d3eb1da9042ec5ff95f0f19\",\"name\":\"M\u00e1rcia Ferreira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"caption\":\"M\u00e1rcia Ferreira\"},\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/author\\\/marcia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista para Editora Pensamento 3 - Sobre a tradu\u00e7\u00e3o do livro \"Jung's Studies in Astrology\" - C.E.A.P.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"Entrevista para Editora Pensamento 3 - Sobre a tradu\u00e7\u00e3o do livro \"Jung's Studies in Astrology\" - C.E.A.P.","og_description":"Nesta entrevista explico sobre a minha recente tradu\u00e7\u00e3o do livro da Liz Greene \u201cJung\u2019s Studies in Astrology\u201d, para a qual fui convidada no in\u00edcio deste ano pelas Editoras Routledge de Londres e Pensamento do Brasil. Explico nesta entrevista sobre a","og_url":"https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/","og_site_name":"C.E.A.P.","article_publisher":"https:\/\/www.facebook.com\/astroceap\/","article_published_time":"2022-06-28T20:29:54+00:00","article_modified_time":"2022-07-08T19:14:12+00:00","og_image":[{"width":750,"height":694,"url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/Entrevista-para-Editora-Pensamento-3-\u2013-Sobre-a-traducao-do-livro-Jungs-Studies-in-Astrology.jpeg","type":"image\/jpeg"}],"author":"M\u00e1rcia Ferreira","twitter_card":"summary_large_image","twitter_creator":"@astrologiaceap","twitter_site":"@astrologiaceap","twitter_misc":{"Escrito por":"M\u00e1rcia Ferreira","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/#article","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/"},"author":{"name":"M\u00e1rcia Ferreira","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/71c3b7859d3eb1da9042ec5ff95f0f19"},"headline":"Entrevista para Editora Pensamento 3 &#8211; Sobre a tradu\u00e7\u00e3o do livro &#8220;Jung&#8217;s Studies in Astrology&#8221;","datePublished":"2022-06-28T20:29:54+00:00","dateModified":"2022-07-08T19:14:12+00:00","mainEntityOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/"},"wordCount":292,"publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/Entrevista-para-Editora-Pensamento-3-\u2013-Sobre-a-traducao-do-livro-Jungs-Studies-in-Astrology.jpeg","keywords":["#cursodeastrologia","#cursosdeastrologia","ascendente","astrologia","astrologia psicol\u00f3gica","astrologiapsicologica","autoconhecimento","casas astrol\u00f3gicas","curso de astrologia","cursos de astrologia","hor\u00f3scopo","infernoastral","Jung","marciaferreira ceap psicologia","mitologia","mitologia grega","planetas","previsoesastrologicas","psicologia","quatroelementos","revolucaosolar","signos","sinastria","transitosastrologicos"],"articleSection":["APRESENTA\u00c7\u00c3O"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/","url":"https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/","name":"Entrevista para Editora Pensamento 3 - Sobre a tradu\u00e7\u00e3o do livro \"Jung's Studies in Astrology\" - C.E.A.P.","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/#primaryimage"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/Entrevista-para-Editora-Pensamento-3-\u2013-Sobre-a-traducao-do-livro-Jungs-Studies-in-Astrology.jpeg","datePublished":"2022-06-28T20:29:54+00:00","dateModified":"2022-07-08T19:14:12+00:00","breadcrumb":{"@id":"https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/#primaryimage","url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/Entrevista-para-Editora-Pensamento-3-\u2013-Sobre-a-traducao-do-livro-Jungs-Studies-in-Astrology.jpeg","contentUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/Entrevista-para-Editora-Pensamento-3-\u2013-Sobre-a-traducao-do-livro-Jungs-Studies-in-Astrology.jpeg","width":750,"height":694},{"@type":"BreadcrumbList","@id":"https:\/\/astroceap.com.br\/ceap\/jung-e-a-astrologia-entrevista-para-editora-pensamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/astroceap.com.br\/ceap\/"},{"@type":"ListItem","position":2,"name":"Entrevista para Editora Pensamento 3 &#8211; Sobre a tradu\u00e7\u00e3o do livro &#8220;Jung&#8217;s Studies in Astrology&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/astroceap.com.br\/ceap\/#website","url":"https:\/\/astroceap.com.br\/ceap\/","name":"C.E.A.P.","description":"Centro de Estudos de Astrologia Psicol\u00f3gica","publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astroceap.com.br\/ceap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/astroceap.com.br\/ceap\/#organization","name":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica","url":"https:\/\/astroceap.com.br\/ceap\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/","url":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","contentUrl":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","width":140,"height":174,"caption":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/astroceap\/","https:\/\/x.com\/astrologiaceap","https:\/\/www.instagram.com\/ceap.astrologia\/","https:\/\/www.youtube.com\/channel\/UCDsKeXx5S7f2xoPUxNpARSQ"]},{"@type":"Person","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/71c3b7859d3eb1da9042ec5ff95f0f19","name":"M\u00e1rcia Ferreira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","caption":"M\u00e1rcia Ferreira"},"url":"https:\/\/astroceap.com.br\/ceap\/author\/marcia\/"}]}},"_links":{"self":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/9043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/comments?post=9043"}],"version-history":[{"count":4,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/9043\/revisions"}],"predecessor-version":[{"id":9079,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/9043\/revisions\/9079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media\/9078"}],"wp:attachment":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media?parent=9043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/categories?post=9043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/tags?post=9043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}