{"id":9052,"date":"2017-06-30T17:59:14","date_gmt":"2017-06-30T20:59:14","guid":{"rendered":"http:\/\/astroceap.com.br\/ceap\/?p=9052"},"modified":"2024-10-28T18:17:27","modified_gmt":"2024-10-28T21:17:27","slug":"evento-sinarj-em-2017","status":"publish","type":"post","link":"https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/","title":{"rendered":"Evento SINARJ em 2017"},"content":{"rendered":"<p dir=\"auto\"><img decoding=\"async\" class=\"size-medium wp-image-9057 aligncenter lazyload\" data-src=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/2-2-300x300.png\" alt=\"\" width=\"300\" height=\"300\" data-srcset=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/2-2-300x300.png 300w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/2-2-1024x1024.png 1024w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/2-2-150x150.png 150w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/2-2-768x768.png 768w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/2-2-230x230.png 230w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/2-2-330x330.png 330w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/2-2.png 1080w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/> <img decoding=\"async\" class=\"size-medium wp-image-9058 aligncenter lazyload\" data-src=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/3-1-300x300.png\" alt=\"\" width=\"300\" height=\"300\" data-srcset=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/3-1-300x300.png 300w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/3-1-1024x1024.png 1024w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/3-1-150x150.png 150w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/3-1-768x768.png 768w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/3-1-230x230.png 230w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/3-1-330x330.png 330w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/3-1.png 1080w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><\/p>\n<p dir=\"auto\"><img decoding=\"async\" class=\"size-medium wp-image-9059 aligncenter lazyload\" data-src=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/4-1-300x300.png\" alt=\"\" width=\"300\" height=\"300\" data-srcset=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/4-1-300x300.png 300w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/4-1-1024x1024.png 1024w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/4-1-150x150.png 150w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/4-1-768x768.png 768w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/4-1-230x230.png 230w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/4-1-330x330.png 330w, https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2022\/06\/4-1.png 1080w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><\/p>\n<p dir=\"auto\">Dei esta palestra no SINARJ &#8211; Sindicato dos Astr\u00f3logos do RJ, em 2017, com o tema:<br \/>\n\u201cUrano e Saturno e a Gera\u00e7\u00e3o dos Anos 40\u201d, fruto de uma pesquisa que eu fiz com os nascidos nos anos 40, onde todos traziam esta conjun\u00e7\u00e3o em seus mapas. Estou falando de: Paul McCartney, Gilberto Gil, Caetano Veloso, Tim Maia, Janis Joplin, Jimi Hendrix, Bob Dylan, Barbra Streisand e tantos outros!<\/p>\n<p dir=\"auto\">Foi e tem sido uma gera\u00e7\u00e3o que marcou uma \u00e9poca! E que trouxe essa qualidade de quebrar paradigmas e padr\u00f5es estabelecidos, tamb\u00e9m de uma certa rebeldia com o status quo e que nos deixou um legado de abertura para coisas novas, assim como est\u00e1 demonstrado por esta conjun\u00e7\u00e3o Urano Saturno em seus mapas e ainda em conjun\u00e7\u00e3o com os nodos! Parece que eles tinham mesmo essa miss\u00e3o revolucion\u00e1ria!<\/p>\n<p dir=\"auto\">A Astrologia, com sua riqueza simb\u00f3lica, nos traz, como no exemplo deste caso, o que existe em comum de t\u00e3o forte e significativo entre pessoas de uma mesma gera\u00e7\u00e3o, e nos d\u00e1 respostas que dificilmente encontrar\u00edamos pelas vias do conhecimento cient\u00edfico tradicional, seja ele psicol\u00f3gico ou de qualquer outra natureza, uma resposta plaus\u00edvel como essa.<\/p>\n<p dir=\"auto\">Com esta conjun\u00e7\u00e3o, podemos entender facilmente como isso se expressou, com Urano que simboliza a quebra de paradigmas e mudan\u00e7as das estruturas, as quais s\u00e3o simbolizadas por Saturno no mapa. Urano, com uma \u00f3rbita de 84 anos e Saturno com uma \u00f3rbita de 28\/30 anos, se encontram a cada 46 anos. Como exemplos mais recentes, temos o auge da 2a Guerra Mundial em 1942 ( pois os planetas j\u00e1 entram em aspecto antes ) e em 1988 a desintegra\u00e7\u00e3o da URSS. A pr\u00f3xima conjun\u00e7\u00e3o se dar\u00e1 em 2034!<br \/>\nO que poderemos esperar de novo e de revolucion\u00e1rio ent\u00e3o? At\u00e9 l\u00e1!<\/p>\n<p dir=\"auto\">E se voc\u00ea gosta desses assuntos interessantes e tamb\u00e9m das interfaces entre psicologia e astrologia, venha nos conhecer! Temos muitos cursos online, artigos e palestras:\u00a0<a href=\"http:\/\/www.astrologiaceap.com.br\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer ugc\">www.astrologiaceap.com.br<\/a><br \/>\nOu siga-nos nas redes sociais: M\u00e1rcia Ferreira Astrologia Psicol\u00f3gica &#8211; FB e Youtube e Instagram:\u00a0<span class=\"atMention\" title=\"marciaferreira\">@marciaferreira<\/span>.astrologiaceap<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dei esta palestra no SINARJ &#8211; Sindicato dos Astr\u00f3logos do RJ, em 2017, com o tema: \u201cUrano e Saturno e a Gera\u00e7\u00e3o dos Anos 40\u201d, fruto de uma pesquisa que eu fiz com os nascidos nos anos 40, onde todos<\/p>\n","protected":false},"author":2,"featured_media":10598,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[31,27],"tags":[133,37,74,82,151,155,153,44,154,36,43,152,38,42],"class_list":["post-9052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-eventos-anteriores","tag-ascendente","tag-astrologia","tag-autoconhecimento","tag-curso-de-astrologia","tag-cursos-online","tag-estudar-astrologia","tag-fases-da-lua","tag-horoscopo","tag-inferno-astral","tag-mapa-astral","tag-planetas","tag-previsoes-astrologicas","tag-psicologia","tag-signos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evento SINARJ em 2017 - C.E.A.P.<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evento SINARJ em 2017 - C.E.A.P.\" \/>\n<meta property=\"og:description\" content=\"Dei esta palestra no SINARJ &#8211; Sindicato dos Astr\u00f3logos do RJ, em 2017, com o tema: \u201cUrano e Saturno e a Gera\u00e7\u00e3o dos Anos 40\u201d, fruto de uma pesquisa que eu fiz com os nascidos nos anos 40, onde todos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"C.E.A.P.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/astroceap\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-30T20:59:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-28T21:17:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2017\/06\/evento_sinarj_2017.png\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"M\u00e1rcia Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:site\" content=\"@astrologiaceap\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00e1rcia Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-sinarj-em-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-sinarj-em-2017\\\/\"},\"author\":{\"name\":\"M\u00e1rcia Ferreira\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/71c3b7859d3eb1da9042ec5ff95f0f19\"},\"headline\":\"Evento SINARJ em 2017\",\"datePublished\":\"2017-06-30T20:59:14+00:00\",\"dateModified\":\"2024-10-28T21:17:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-sinarj-em-2017\\\/\"},\"wordCount\":357,\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-sinarj-em-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/evento_sinarj_2017.png\",\"keywords\":[\"ascendente\",\"astrologia\",\"autoconhecimento\",\"curso de astrologia\",\"cursos online\",\"estudar astrologia\",\"fases da lua\",\"hor\u00f3scopo\",\"inferno astral\",\"mapa astral\",\"planetas\",\"previs\u00f5es astrol\u00f3gicas\",\"psicologia\",\"signos\"],\"articleSection\":[\"EVENTOS\",\"EVENTOS ANTERIORES\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-sinarj-em-2017\\\/\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-sinarj-em-2017\\\/\",\"name\":\"Evento SINARJ em 2017 - C.E.A.P.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-sinarj-em-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-sinarj-em-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/evento_sinarj_2017.png\",\"datePublished\":\"2017-06-30T20:59:14+00:00\",\"dateModified\":\"2024-10-28T21:17:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-sinarj-em-2017\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-sinarj-em-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-sinarj-em-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/evento_sinarj_2017.png\",\"contentUrl\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/evento_sinarj_2017.png\",\"width\":480,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/evento-sinarj-em-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evento SINARJ em 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#website\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"name\":\"C.E.A.P.\",\"description\":\"Centro de Estudos de Astrologia Psicol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#organization\",\"name\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\",\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"contentUrl\":\"http:\\\/\\\/astroceap.com.br\\\/ceap\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO_CEAP_New4site.jpg\",\"width\":140,\"height\":174,\"caption\":\"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica\"},\"image\":{\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/astroceap\\\/\",\"https:\\\/\\\/x.com\\\/astrologiaceap\",\"https:\\\/\\\/www.instagram.com\\\/ceap.astrologia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDsKeXx5S7f2xoPUxNpARSQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/#\\\/schema\\\/person\\\/71c3b7859d3eb1da9042ec5ff95f0f19\",\"name\":\"M\u00e1rcia Ferreira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g\",\"caption\":\"M\u00e1rcia Ferreira\"},\"url\":\"https:\\\/\\\/astroceap.com.br\\\/ceap\\\/author\\\/marcia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evento SINARJ em 2017 - C.E.A.P.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"Evento SINARJ em 2017 - C.E.A.P.","og_description":"Dei esta palestra no SINARJ &#8211; Sindicato dos Astr\u00f3logos do RJ, em 2017, com o tema: \u201cUrano e Saturno e a Gera\u00e7\u00e3o dos Anos 40\u201d, fruto de uma pesquisa que eu fiz com os nascidos nos anos 40, onde todos","og_url":"https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/","og_site_name":"C.E.A.P.","article_publisher":"https:\/\/www.facebook.com\/astroceap\/","article_published_time":"2017-06-30T20:59:14+00:00","article_modified_time":"2024-10-28T21:17:27+00:00","og_image":[{"width":480,"height":300,"url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2017\/06\/evento_sinarj_2017.png","type":"image\/png"}],"author":"M\u00e1rcia Ferreira","twitter_card":"summary_large_image","twitter_creator":"@astrologiaceap","twitter_site":"@astrologiaceap","twitter_misc":{"Escrito por":"M\u00e1rcia Ferreira","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/#article","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/"},"author":{"name":"M\u00e1rcia Ferreira","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/71c3b7859d3eb1da9042ec5ff95f0f19"},"headline":"Evento SINARJ em 2017","datePublished":"2017-06-30T20:59:14+00:00","dateModified":"2024-10-28T21:17:27+00:00","mainEntityOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/"},"wordCount":357,"publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2017\/06\/evento_sinarj_2017.png","keywords":["ascendente","astrologia","autoconhecimento","curso de astrologia","cursos online","estudar astrologia","fases da lua","hor\u00f3scopo","inferno astral","mapa astral","planetas","previs\u00f5es astrol\u00f3gicas","psicologia","signos"],"articleSection":["EVENTOS","EVENTOS ANTERIORES"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/","url":"https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/","name":"Evento SINARJ em 2017 - C.E.A.P.","isPartOf":{"@id":"https:\/\/astroceap.com.br\/ceap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/#primaryimage"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2017\/06\/evento_sinarj_2017.png","datePublished":"2017-06-30T20:59:14+00:00","dateModified":"2024-10-28T21:17:27+00:00","breadcrumb":{"@id":"https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/#primaryimage","url":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2017\/06\/evento_sinarj_2017.png","contentUrl":"https:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2017\/06\/evento_sinarj_2017.png","width":480,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/astroceap.com.br\/ceap\/evento-sinarj-em-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/astroceap.com.br\/ceap\/"},{"@type":"ListItem","position":2,"name":"Evento SINARJ em 2017"}]},{"@type":"WebSite","@id":"https:\/\/astroceap.com.br\/ceap\/#website","url":"https:\/\/astroceap.com.br\/ceap\/","name":"C.E.A.P.","description":"Centro de Estudos de Astrologia Psicol\u00f3gica","publisher":{"@id":"https:\/\/astroceap.com.br\/ceap\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astroceap.com.br\/ceap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/astroceap.com.br\/ceap\/#organization","name":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica","url":"https:\/\/astroceap.com.br\/ceap\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/","url":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","contentUrl":"http:\/\/astroceap.com.br\/ceap\/wp-content\/uploads\/2018\/03\/LOGO_CEAP_New4site.jpg","width":140,"height":174,"caption":"CEAP Centro de Estudos de Astrologia Psicol\u00f3gica"},"image":{"@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/astroceap\/","https:\/\/x.com\/astrologiaceap","https:\/\/www.instagram.com\/ceap.astrologia\/","https:\/\/www.youtube.com\/channel\/UCDsKeXx5S7f2xoPUxNpARSQ"]},{"@type":"Person","@id":"https:\/\/astroceap.com.br\/ceap\/#\/schema\/person\/71c3b7859d3eb1da9042ec5ff95f0f19","name":"M\u00e1rcia Ferreira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd5059b36d5063d13f9031bfc2c2a33f58aa52a789609b08717cc48b711f9b3f?s=96&d=blank&r=g","caption":"M\u00e1rcia Ferreira"},"url":"https:\/\/astroceap.com.br\/ceap\/author\/marcia\/"}]}},"_links":{"self":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/9052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/comments?post=9052"}],"version-history":[{"count":4,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/9052\/revisions"}],"predecessor-version":[{"id":10597,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/posts\/9052\/revisions\/10597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media\/10598"}],"wp:attachment":[{"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/media?parent=9052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/categories?post=9052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astroceap.com.br\/ceap\/wp-json\/wp\/v2\/tags?post=9052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}